{"id":863,"date":"2009-04-10T07:27:03","date_gmt":"2009-04-10T05:27:03","guid":{"rendered":"http:\/\/lamissive.4ailes.free.fr\/wordpress\/?p=863"},"modified":"2009-04-10T07:27:03","modified_gmt":"2009-04-10T05:27:03","slug":"la-symphonie-fantastique","status":"publish","type":"post","link":"https:\/\/www.collectif4ailes.fr\/blog\/la-symphonie-fantastique\/","title":{"rendered":"La symphonie fantastique"},"content":{"rendered":"<p>Voici le film court r\u00e9alis\u00e9 avec les enfants de CM2 de l&rsquo;\u00e9cole Voltaire \u00e0 Denain.<\/p>\n<p>Le principe :<\/p>\n<ul>\n<li>Une promenade dans la ville avec les enseignants<\/li>\n<li>Un r\u00e9cit unique de la promenade (les d\u00e9tails observ\u00e9s ouvrent la portent au merveilleux)<\/li>\n<li>Un storyboard<\/li>\n<li>La conception des d\u00e9cors en ombres<\/li>\n<li>Le tournage sur le principe du th\u00e9\u00e2tre d&rsquo;ombres et du cin\u00e9ma<\/li>\n<\/ul>\n<p><object width=\"480\" height=\"385\"><param name=\"movie\" value=\"http:\/\/www.youtube-nocookie.com\/v\/xbbyRpwYVe4&#038;hl=fr&#038;fs=1&#038;rel=0&#038;color1=0x3a3a3a&#038;color2=0x999999&#038;hd=1\"><\/param><param name=\"allowFullScreen\" value=\"true\"><\/param><param name=\"allowscriptaccess\" value=\"always\"><\/param><embed src=\"http:\/\/www.youtube-nocookie.com\/v\/xbbyRpwYVe4&#038;hl=fr&#038;fs=1&#038;rel=0&#038;color1=0x3a3a3a&#038;color2=0x999999\" type=\"application\/x-shockwave-flash\" allowscriptaccess=\"always\" allowfullscreen=\"true\" width=\"480\" height=\"385\"><\/embed><\/object><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Voici le film court r\u00e9alis\u00e9 avec les enfants de CM2 de l&rsquo;\u00e9cole Voltaire \u00e0 Denain. Le principe : Une promenade dans la ville avec les enseignants Un r\u00e9cit unique de la promenade (les d\u00e9tails observ\u00e9s ouvrent la portent au merveilleux) Un storyboard La conception des d\u00e9cors en ombres Le tournage sur le principe du th\u00e9\u00e2tre &hellip; <a href=\"https:\/\/www.collectif4ailes.fr\/blog\/la-symphonie-fantastique\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;La symphonie fantastique&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-863","post","type-post","status-publish","format-standard","hentry","category-actualite"],"_links":{"self":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/863","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/comments?post=863"}],"version-history":[{"count":0,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/863\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/media?parent=863"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/categories?post=863"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/tags?post=863"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}