{"id":849,"date":"2009-03-26T06:47:59","date_gmt":"2009-03-26T05:47:59","guid":{"rendered":"http:\/\/lamissive.4ailes.free.fr\/wordpress\/?p=849"},"modified":"2009-03-26T06:47:59","modified_gmt":"2009-03-26T05:47:59","slug":"apres-les-ateliers-a-denain-lecole-voltaire-nous-offre-un-bout-du-nord","status":"publish","type":"post","link":"https:\/\/www.collectif4ailes.fr\/blog\/apres-les-ateliers-a-denain-lecole-voltaire-nous-offre-un-bout-du-nord\/","title":{"rendered":"Apr\u00e8s les ateliers \u00e0 Denain l&rsquo;\u00e9cole Voltaire nous offre un bout du Nord"},"content":{"rendered":"<p style=\"text-align: left;\"><a href=\"http:\/\/lamissive.4ailes.free.fr\/wordpress\/wp-content\/2009\/03\/cafougnette-recto.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-850 alignleft\" title=\"cafougnette-recto\" src=\"http:\/\/lamissive.4ailes.free.fr\/wordpress\/wp-content\/2009\/03\/cafougnette-recto.jpg\" alt=\"cafougnette-recto\" width=\"180\" height=\"246\" \/><\/a><a href=\"http:\/\/lamissive.4ailes.free.fr\/wordpress\/wp-content\/2009\/03\/cafougnette-verso.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-851 alignnone\" title=\"cafougnette-verso\" src=\"http:\/\/lamissive.4ailes.free.fr\/wordpress\/wp-content\/2009\/03\/cafougnette-verso.jpg\" alt=\"cafougnette-verso\" width=\"180\" height=\"246\" \/><\/a><\/p>\n<p style=\"text-align: left;\">Magali (enseignante en acier tremp\u00e9e et en macarons \u00e0 tomber par terre) et sa classe de CM2 nous ont offert une BD qui retrace les histoires de <strong>Cafougnette<\/strong> un personnage mythique du Nord de la France. <a href=\"http:\/\/fr.wikipedia.org\/wiki\/Cafougnette\" target=\"_blank\">Pour en savoir plus jetez un oeil ici<\/a>.<\/p>\n<p style=\"text-align: left;\">Ce cadeau nous a \u00e9t\u00e9 remis en patois denaisien (s&rsquo;il vous plait !!!) et avec beaucoup de d&rsquo;humour et d&rsquo;\u00e9motions. Ci dessous une image de ce pr\u00e9sent achet\u00e9 dans le temple de la culture du Nord&#8230; <a href=\"http:\/\/fr.wikipedia.org\/wiki\/Furet_du_Nord\" target=\"_blank\"><strong>Le Furet du Nord <\/strong><\/a><\/p>\n<p style=\"text-align: left;\">\n<p style=\"text-align: left;\">\n","protected":false},"excerpt":{"rendered":"<p>Magali (enseignante en acier tremp\u00e9e et en macarons \u00e0 tomber par terre) et sa classe de CM2 nous ont offert une BD qui retrace les histoires de Cafougnette un personnage mythique du Nord de la France. Pour en savoir plus jetez un oeil ici. Ce cadeau nous a \u00e9t\u00e9 remis en patois denaisien (s&rsquo;il vous &hellip; <a href=\"https:\/\/www.collectif4ailes.fr\/blog\/apres-les-ateliers-a-denain-lecole-voltaire-nous-offre-un-bout-du-nord\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;Apr\u00e8s les ateliers \u00e0 Denain l&rsquo;\u00e9cole Voltaire nous offre un bout du Nord&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,7,10,11],"tags":[],"class_list":["post-849","post","type-post","status-publish","format-standard","hentry","category-actualite","category-coup-de-coeur","category-spectacles-et-creation","category-vie-du-collectif"],"_links":{"self":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/849","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/comments?post=849"}],"version-history":[{"count":0,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/849\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/media?parent=849"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/categories?post=849"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/tags?post=849"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}