{"id":723,"date":"2009-02-09T20:00:32","date_gmt":"2009-02-09T19:00:32","guid":{"rendered":"http:\/\/lamissive.4ailes.free.fr\/wordpress\/?p=723"},"modified":"2009-02-09T20:00:32","modified_gmt":"2009-02-09T19:00:32","slug":"la-cuisine-des-superheros-7","status":"publish","type":"post","link":"https:\/\/www.collectif4ailes.fr\/blog\/la-cuisine-des-superheros-7\/","title":{"rendered":"La Cuisine de Ratata Reine de Kiche"},"content":{"rendered":"<p><strong>Tranch\u00e9s, hach\u00e9s, cuits et recuits, nos superh\u00e9ros culinaires sont enfin \u00e0 point. Pas b\u00e9gueules, deux d\u2019entre eux se livrent \u00e0 vous chaque semaine, sans autre pr\u00e9tention litt\u00e9raire que de vous amuser ou vous faire sourire. Vous reprendrez bien une louche de superpouvoirs ?<\/strong><\/p>\n<p><strong><a href=\"http:\/\/lamissive.4ailes.free.fr\/wordpress\/?p=601\">Lire la pr\u00e9face<\/a><\/strong><\/p>\n<p><strong><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-734\" title=\"missive_ratata-reine-de-kiche\" src=\"http:\/\/lamissive.4ailes.free.fr\/wordpress\/wp-content\/missive_ratata-reine-de-kiche.jpg\" alt=\"missive_ratata-reine-de-kiche\" width=\"333\" height=\"555\" \/><br \/>\n<\/strong><\/strong><\/p>\n<p><strong>Nom l\u00e9gendaire :<\/strong> Ratata Reine de Kiche<\/p>\n<p><strong>Identit\u00e9 r\u00e9elle\u00a0 :<\/strong> Marie Lorieux<\/p>\n<p><strong>Sexe :<\/strong> f\u00e9minin<\/p>\n<p><strong>Taille et poids\u00a0 :<\/strong> variables \u00e0 volont\u00e9 quand elle est sur Terre, sinon 1,80 m et 70 kg.<\/p>\n<p><strong>Yeux :<\/strong> verts et bleus<\/p>\n<p><strong>Cheveux :<\/strong> ch\u00e2tains dans la vie, violets quand elle est Ratata la Justici\u00e8re<\/p>\n<p><strong>Peau :<\/strong> blanche dans la vie, vert d\u2019eau quand elle est Ratata<\/p>\n<p><strong>Base :<\/strong> Plan\u00e8te Kiche, palais royal \u00ab Solanacia \u00bb<\/p>\n<p><strong>Premi\u00e8re apparition :<\/strong> vers 1850<\/p>\n<p><strong>Costume et apparence :<\/strong> tenue de contractuelle compos\u00e9e de cristaux de sel et de lianes.<\/p>\n<p><strong>Type de cuisine favorite :<\/strong> v\u00e9g\u00e9tarienne<\/p>\n<p><strong>Cat\u00e9gorie :<\/strong> vraiment gentille<\/p>\n<p><strong>Ennemis :<\/strong> les omnivores, les voisins qui ne font pas le tri s\u00e9lectif, le stationnement altern\u00e9.<\/p>\n<p><strong>Expression f\u00e9tiche :<\/strong> \u00ab Nom d\u2019une Quiche en bois\u00a0 !!! \u00bb<\/p>\n<p><strong>Humeur, particularit\u00e9, nature des pouvoirs :<\/strong> Ratata Reine de Kiche se distingue par son maintien et sa grande douceur. Toujours aimable, polie et convenablement v\u00eatue, elle se r\u00e9jouit de plaisirs simples. Elle aime \u00e0 se p\u00e2mer dans sa cuisine en parlant aux l\u00e9gumes. La sympathie qu\u2019elle d\u00e9gage n\u2019en fait pas moins une farouche cuisini\u00e8re. Elle est notamment engag\u00e9e dans le combat pour l\u2019usage de produits 100% biologiques et \u00e9quitables. Plut\u00f4t pacifique, Ratata ma\u00eetrise\u00a0 les techniques de combat de la Quiche. Elle commande aux l\u00e9gumes par ondes t\u00e9l\u00e9pathiques. Elle emprisonne ses victimes dans des cercueils alcalins en projetant des filaments de sodium depuis sa chevelure. Lorsqu&rsquo;elle est en grand danger, elle projette le souffle de l&rsquo;ivresse des profondeurs qui concentre de tr\u00e8s fortes doses de mandragore et de belladone, tuant sa victime avec douceur.<\/p>\n<p><!--more--><\/p>\n<p class=\"western\"><span><br \/>\n<\/span><\/p>\n<p class=\"western\"><strong><span><span>Origine des pouvoirs \/ Histoire\u00a0:<\/span><\/span><\/strong><\/p>\n<p>Depuis des milliers d&rsquo;ann\u00e9es, les futures souveraines de la plan\u00e8te Kiche sont envoy\u00e9es secr\u00e8tement sur la Terre pour recevoir une \u00e9ducation royale. La rigueur et le raffinement des pensionnats terriens ont en effet toujours su faire des t\u00eates couronn\u00e9es de Kiche la cr\u00e8me de la cr\u00e8me des reines intergalactiques.<\/p>\n<p>C\u2019est ainsi que la petite Ratata, fille de Courge la Grande et de Patates Feuillet\u00e9es, apprit les r\u00e8gles de savoir-vivre et de maintien d&rsquo;une femme du monde dans le tr\u00e8s renomm\u00e9 pensionnat de jeunes filles \u00abLes F\u00e9es de Remiremont \u00bb, situ\u00e9 en en Lorraine. Lors de sa deuxi\u00e8me ann\u00e9e au pensionnat, elle d\u00e9couvrit que derri\u00e8re son professeur d&rsquo;\u00e9ducation physique et sportive se cachait Suzy One, la ma\u00eetresse d&rsquo;armes de Solanacia, le palais de ses chers parents. Suzy One avait travers\u00e9 l\u2019espace\u00a0 par le r\u00e9seau secret Rice Kooker II dans le but de la prot\u00e9ger. \u00c0 l&rsquo;abri dans le potager du clo\u00eetre voisin, Suzy One transmit \u00e0 la princesse les secrets des pouvoirs de Kiche. Mais les entra\u00eenements \u00e9veill\u00e8rent la curiosit\u00e9 des moines qui se demandaient pourquoi cette \u00e9coli\u00e8re parlait aux poireaux et aux asperges. La jeune princesse acheta leur silence en d\u00e9cuplant la taille de leurs l\u00e9gumes. Op\u00e9ration qui valut au clo\u00eetre la r\u00e9putation des plus gros poireaux de la r\u00e9gion.<br \/>\nAlors que la jeune princesse f\u00eatait ses 20 ans sur Terre, une terrible guerre \u00e9clata sur Kiche. Le conflit opposait le palais de Solanacia \u00e0 la terrible et redoutable Herqueuche de Flamme Kueche. Suzy One fut rappel\u00e9e par le palais pour prendre le commandement d\u2019un groupe de tireuses d\u2019\u00e9lites. D\u00e9sormais, Ratata \u00e9tait seule et exil\u00e9e car il lui \u00e9tait impossible de retourner sur sa plan\u00e8te tant que Herqueuche n\u2019aurait pas rendu les armes.<\/p>\n<p>Dans l\u2019incapacit\u00e9 de poursuivre ses \u00e9tudes, abandonn\u00e9e et impuissante, elle partit \u00e0 la d\u00e9couverte du monde et finit par poser ses valises dans la petite bourgade de Walnut Grove. L\u00e0, connue sous le nom de Caroline, elle dissimula ses atours de reine sous l&rsquo;apparence modeste d&rsquo;une fille de ferme.<\/p>\n<p>Quelques ann\u00e9es apr\u00e8s,\u00a0 elle rencontra Charles, un homme fid\u00e8le et travailleur, aim\u00e9 de ses voisins et passionn\u00e9 par la coupe du bois.\u00a0 Cette activit\u00e9 virile l&rsquo;\u00e9loignait de longs mois durant du magnifique pavillon en rondins qu&rsquo;il avait lui-m\u00eame construit. Ratata profitait des interminables absences de son mari pour laisser s\u2019exprimer\u00a0 sa vraie nature. Elle communiait avec les l\u00e9gumes gorg\u00e9s de soleil de son jardinet. Il fallait la voir courant dans la verdure en riant. Elle tournait sur elle-m\u00eame en racontant ses meilleures blagues aux v\u00e9g\u00e9taux. Elle inventait de nombreuses recettes comme la tarte \u00e0 la boue et aux olives. Elle menait pour tout dire une existence paisible et gaie. Mais un jour, tout bascula. Catherine, l&rsquo;a\u00een\u00e9e de ses filles, rentrait de l&rsquo;\u00e9cole o\u00f9 Mademoiselle Mangin lui avait donn\u00e9 un C- pour son expos\u00e9. Une note pas fameuse pour une jeune fille de 14 ans en CP. Elle tra\u00eenait les pieds sur le trajet du retour. Soudain, surgissant \u00e0 toute vitesse sur la route poussi\u00e9reuse, une charrette folle se pr\u00e9cipita vers elle. Le choc fut terrible et la fillette perdit la vue, l&rsquo;usage de ses jambes et son cartable.<\/p>\n<p>Catherine devint un poids mort pour la famille. Totalement d\u00e9pressive,\u00a0 elle noyait son chagrin dans la consommation abusive de barres chocolat\u00e9es tr\u00e8s caloriques.\u00a0 Malgr\u00e9 les interdictions de sa m\u00e8re, Lorraine, la fille du confiseur, prenait un plaisir pervers \u00e0 lui offrir des cadeaux sucr\u00e9s. Cul-de-jatte, ob\u00e8se, aveugle, gravement d\u00e9pressive et analphab\u00e8te, Catherine souffrait. La Reine Ratata endormit \u00e0 tout jamais les souffrances de sa fille en usant de son souffle de l\u2019ivresse des profondeurs. Traumatis\u00e9e, La Reine quitta Walnut Grove et jura de venger sa fille. Charles, qui \u00e9tait un homme juste et bon, ne supporta pas bien longtemps la disparition inexpliqu\u00e9e de son \u00e9pouse.\u00a0 Il sombra dans l\u2019enfer de la drogue et de la prostitution.<br \/>\nRatata de son c\u00f4t\u00e9 suivit la piste de la charrette folle et devint progressivement une experte dans les sciences de la circulation automobile. Elle connaissait par c\u0153ur les codes de la route des r\u00e9gions qu\u2019elle franchissait, on lui pr\u00eate m\u00eame l\u2019invention des plaques min\u00e9ralogiques. Sa qu\u00eate la mena en France, \u00e0 Paris. Mais \u00e9puis\u00e9e par ses cinq ann\u00e9es de recherche, elle abandonna sa course folle. Elle reprit une vie normale et devint contractuelle sous le nom de Marie Lorieux. \u00c0 partir de ce jour, elle mit ses pouvoirs au service de la justice. Avec l\u2019aide complice des fruits et l\u00e9gumes, elle sortait toujours victorieuse. Usant de sa connaissance du code de la route et de ses superpouvoirs, Ratata mit au point un savant quadrillage de son secteur de surveillance.\u00a0 Elle pactisa avec les jardins de ronds-points, les bacs \u00e0 fleurs municipaux, les jardini\u00e8res de balcons, les squares et les jardinets des \u00e9choppes pour d\u00e9velopper un gigantesque r\u00e9seau v\u00e9g\u00e9tal de d\u00e9lation. \u00c0 la t\u00eate de cette organisation secr\u00e8te Ratata tenait les contrevenants de son secteur\u00a0 d\u2019une main de fer.\u00a0 Par ailleurs, Ratata\u00a0 n\u2019h\u00e9sitait pas \u00e0 pi\u00e9ger ses victimes avec ses irr\u00e9sistibles petits plats. Plus d\u2019une fois enlev\u00e9e et s\u00e9questr\u00e9e elle se sortait d\u2019affaire \u00e0 l\u2019aide de ses quiches hallucinog\u00e8nes. Sans piti\u00e9 pour les m\u00e9chants, elle pouvait se montrer d\u2019une cruaut\u00e9 sans nom. La presse nationale a longuement retrac\u00e9 ses aventures. On se souvient encore de titres comme : \u00ab Ratata et le gang des chauffards \u00bb, \u00ab Une quiche vaut mieux que deux tu l\u2019auras \u00bb ou encore \u00ab\u00a0 Trahie par ses l\u00e9gumes !!! \u00bb.<\/p>\n<p><span style=\"font-size: x-small;\"><span style=\"font-family: Verdana;\"><br \/>\n<\/span><\/span><\/p>\n<p><strong><span style=\"color: #000000;\">La suite au prochain \u00e9pisode avec Poulpa !<\/span><\/strong><\/p>\n<p><strong><span style=\"color: #000000;\"><br \/>\n<\/span><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tranch\u00e9s, hach\u00e9s, cuits et recuits, nos superh\u00e9ros culinaires sont enfin \u00e0 point. Pas b\u00e9gueules, deux d\u2019entre eux se livrent \u00e0 vous chaque semaine, sans autre pr\u00e9tention litt\u00e9raire que de vous amuser ou vous faire sourire. Vous reprendrez bien une louche de superpouvoirs ? Lire la pr\u00e9face Nom l\u00e9gendaire : Ratata Reine de Kiche Identit\u00e9 r\u00e9elle\u00a0 &hellip; <a href=\"https:\/\/www.collectif4ailes.fr\/blog\/la-cuisine-des-superheros-7\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;La Cuisine de Ratata Reine de Kiche&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-723","post","type-post","status-publish","format-standard","hentry","category-la-cuisine-des-superheros"],"_links":{"self":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/723","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/comments?post=723"}],"version-history":[{"count":1,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/723\/revisions"}],"predecessor-version":[{"id":2309,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/723\/revisions\/2309"}],"wp:attachment":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/media?parent=723"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/categories?post=723"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/tags?post=723"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}