{"id":6161,"date":"2022-01-13T17:23:39","date_gmt":"2022-01-13T16:23:39","guid":{"rendered":"https:\/\/www.collectif4ailes.fr\/blog\/?p=6161"},"modified":"2022-01-13T17:44:29","modified_gmt":"2022-01-13T16:44:29","slug":"non-loin-de-toulouse-certains-regardent-les-etoiles","status":"publish","type":"post","link":"https:\/\/www.collectif4ailes.fr\/blog\/non-loin-de-toulouse-certains-regardent-les-etoiles\/","title":{"rendered":"Non loin de Toulouse, Certains regardent les \u00e9toiles"},"content":{"rendered":"\n\n\n<p>Gabrielle, Victor et toute la constellation de personnages qui les suit seront cette fin de semaine en Occitanie \u00e0 Ramonville (\u00e0 quelques stations de m\u00e9tro de Toulouse). C&rsquo;est donc une ann\u00e9e 2022 qui commence sous le signe de la tourn\u00e9e car cher public juste apr\u00e8s l&rsquo;Occitanie nous visiterons les terres franciliennes vous pourrez retrouver <strong><em>Certains regardent les \u00e9toiles<\/em><\/strong> aussi \u00e0 Anis gras &#8211; le lieu de l&rsquo;autre (Arcueil) d\u00e8s le 25 janvier. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"a-ramonville-toulouse\">\u00e0 Ramonville (Toulouse)<\/h2>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Repr\u00e9sentations le 14 janvier \u00e0 14h30 et le 15 \u00e0 17h00 au Kiwi <\/strong><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2022\/01\/Capture-de\u0301cran-2022-01-13-a\u0300-17.38.29.webp\" alt=\"Logo accessibilit\u00e9 des repr\u00e9sentations de certains regardent les \u00e9toiles au public sourd et handicap\u00e9\" class=\"wp-image-6182\" width=\"98\" height=\"57\" srcset=\"https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2022\/01\/Capture-de\u0301cran-2022-01-13-a\u0300-17.38.29.webp 182w, https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2022\/01\/Capture-de\u0301cran-2022-01-13-a\u0300-17.38.29-150x87.webp 150w\" sizes=\"auto, (max-width: 98px) 85vw, 98px\" \/><\/figure><\/div>\n\n\n\n<p>Pour la premi\u00e8re fois le spectacle sera rendu accessible avec une traduction simultan\u00e9e en <strong>LSF<\/strong> (Langue des Signes Fran\u00e7aise). Une exp\u00e9rimentation dans la continuit\u00e9 du travail men\u00e9 sur <em><strong>apr\u00e8s le tremblement de terre<\/strong><\/em> avec Acc\u00e8s Culture. \u00c0 la suite de cette exp\u00e9rimentation nous aimerions mener un travail d&rsquo;int\u00e9gration plus pouss\u00e9e de la LSF dans le spectacle pour disposer d&rsquo;une version permettant de partager plus harmonieusement les repr\u00e9sentations.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2022\/01\/Capture-de\u0301cran-2022-01-13-a\u0300-16.04.58-1024x241.webp\" alt=\"Certains regardent les \u00e9toiles \u00e0 Ramonville\" class=\"wp-image-6167\" width=\"554\" height=\"129\" srcset=\"https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2022\/01\/Capture-de\u0301cran-2022-01-13-a\u0300-16.04.58-1024x241.webp 1024w, https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2022\/01\/Capture-de\u0301cran-2022-01-13-a\u0300-16.04.58-300x71.webp 300w, https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2022\/01\/Capture-de\u0301cran-2022-01-13-a\u0300-16.04.58-150x35.webp 150w\" sizes=\"auto, (max-width: 554px) 85vw, 554px\" \/><\/figure>\n\n\n\n<div class=\"wp-block-material-buttons\">\n<div class=\"wp-block-material-button\" id=\"block-material-button-0\"><a href=\"https:\/\/kiwiramonville-arto.fr\/evenement\/certains-regardent-les-etoiles\/\" class=\"mdc-button mdc-button--raised\"><i class=\"material-icons mdc-button__icon\">theater_comedy<\/i><div class=\"mdc-button__ripple\"><\/div><span class=\"mdc-button__label\">R\u00e9server<\/span><\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"a-ramonville-toulouse\">\u00e0 Arcueil (Paris)<\/h2>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Repr\u00e9sentations le 25 janvier au 30 janvier \u00e0 Anis gras &#8211; Le lieu de l&rsquo;autre <\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2022\/01\/Capture-de\u0301cran-2022-01-13-a\u0300-16.24.35-1024x288.webp\" alt=\"Certains regardent les \u00e9toiles \u00e0 Arcueil\" class=\"wp-image-6166\" width=\"538\" height=\"151\" srcset=\"https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2022\/01\/Capture-de\u0301cran-2022-01-13-a\u0300-16.24.35-1024x288.webp 1024w, https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2022\/01\/Capture-de\u0301cran-2022-01-13-a\u0300-16.24.35-300x84.webp 300w, https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2022\/01\/Capture-de\u0301cran-2022-01-13-a\u0300-16.24.35-768x216.webp 768w, https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2022\/01\/Capture-de\u0301cran-2022-01-13-a\u0300-16.24.35-1536x432.webp 1536w, https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2022\/01\/Capture-de\u0301cran-2022-01-13-a\u0300-16.24.35-150x42.webp 150w, https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2022\/01\/Capture-de\u0301cran-2022-01-13-a\u0300-16.24.35.webp 1940w\" sizes=\"auto, (max-width: 538px) 85vw, 538px\" \/><\/figure>\n\n\n\n<div class=\"wp-block-material-buttons\">\n<div class=\"wp-block-material-button\" id=\"block-material-button-11\"><a href=\"https:\/\/lelieudelautre.mapado.com\/event\/69367-certains-regardent-les-etoiles-collectif-quatre-ailes\" class=\"mdc-button mdc-button--raised\"><i class=\"material-icons mdc-button__icon\">theater_comedy<\/i><div class=\"mdc-button__ripple\"><\/div><span class=\"mdc-button__label\">r\u00e9server<\/span><\/a><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Gabrielle, Victor et toute la constellation de personnages qui les suit seront cette fin de semaine en Occitanie \u00e0 Ramonville (\u00e0 quelques stations de m\u00e9tro de Toulouse). C&rsquo;est donc une ann\u00e9e 2022 qui commence sous le signe de la tourn\u00e9e car cher public juste apr\u00e8s l&rsquo;Occitanie nous visiterons les terres franciliennes vous pourrez retrouver Certains &hellip; <a href=\"https:\/\/www.collectif4ailes.fr\/blog\/non-loin-de-toulouse-certains-regardent-les-etoiles\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;Non loin de Toulouse, Certains regardent les \u00e9toiles&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":6177,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-6161","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite"],"_links":{"self":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/6161","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/comments?post=6161"}],"version-history":[{"count":14,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/6161\/revisions"}],"predecessor-version":[{"id":6183,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/6161\/revisions\/6183"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/media\/6177"}],"wp:attachment":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/media?parent=6161"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/categories?post=6161"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/tags?post=6161"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}