{"id":5873,"date":"2021-04-22T11:58:47","date_gmt":"2021-04-22T09:58:47","guid":{"rendered":"https:\/\/www.collectif4ailes.fr\/blog\/?p=5873"},"modified":"2021-08-08T15:35:18","modified_gmt":"2021-08-08T13:35:18","slug":"les-improbables-representations","status":"publish","type":"post","link":"https:\/\/www.collectif4ailes.fr\/blog\/les-improbables-representations\/","title":{"rendered":"Les improbables repr\u00e9sentations"},"content":{"rendered":"\n<p>Alors que nous accumulons comme toutes les professions culturelles annulations et reports. Au coeur de la temp\u00eate nous avons eu par la magie des proc\u00e9dures administratives la possibilit\u00e9 de reprendre la tourn\u00e9e de <em>Certains regardent les \u00e9toiles<\/em> fin mars dernier. Une bulle totalement improbable, dans un th\u00e9\u00e2tre et pour quelques repr\u00e9sentations exclusivement r\u00e9serv\u00e9es au public scolaire et avec tout son arsenal indispensable de mesures sanitaires. <\/p>\n\n\n\n<p>Mais nous avons jou\u00e9  !!! <\/p>\n\n\n\n<p>Et au-del\u00e0 du plaisir immense de retrouver un plateau et un public vivant, c&rsquo;\u00e9tait pour Damien un retour \u00e0 l&rsquo;endroit m\u00eame o\u00f9 le th\u00e9\u00e2tre est devenu aussi essentiel qu&rsquo;indispensable pour lui. L&rsquo;endroit o\u00f9 tout a commenc\u00e9 ! Et c&rsquo;est avec beaucoup de douceur que l&rsquo;\u00e9quipe du th\u00e9\u00e2tre et de la ville ont orchestr\u00e9 un portait dans le journal de Lormont. Un article de Bernard Bris\u00e9 \u00e0 d\u00e9couvrir <a href=\"https:\/\/www.lormont.fr\/actualites-109\/damien-saugeon-entre-reel-et-comedie-humaine-3788.html\" target=\"_blank\" rel=\"noreferrer noopener\">ici<\/a><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2021\/04\/Capture-de\u0301cran-2021-04-22-a\u0300-11.45.45.png\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"201\" src=\"https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2021\/04\/Capture-de\u0301cran-2021-04-22-a\u0300-11.45.45-1024x201.png\" alt=\"\" class=\"wp-image-5874\" srcset=\"https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2021\/04\/Capture-de\u0301cran-2021-04-22-a\u0300-11.45.45-1024x201.png 1024w, https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2021\/04\/Capture-de\u0301cran-2021-04-22-a\u0300-11.45.45-300x59.png 300w, https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2021\/04\/Capture-de\u0301cran-2021-04-22-a\u0300-11.45.45-768x150.png 768w, https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2021\/04\/Capture-de\u0301cran-2021-04-22-a\u0300-11.45.45-1536x301.png 1536w, https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2021\/04\/Capture-de\u0301cran-2021-04-22-a\u0300-11.45.45-2048x401.png 2048w, https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2021\/04\/Capture-de\u0301cran-2021-04-22-a\u0300-11.45.45-150x29.png 150w\" sizes=\"auto, (max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><\/a><figcaption>Photo : S. Gomez Lechaptois<\/figcaption><\/figure>\n\n\n\n<div class=\"wp-block-material-buttons\">\n<div class=\"wp-block-material-button\" id=\"block-material-button-0\"><a href=\"https:\/\/www.lormont.fr\/actualites-109\/damien-saugeon-entre-reel-et-comedie-humaine-3788.html\" class=\"mdc-button mdc-button--outlined\"><i class=\"material-icons mdc-button__icon\">article<\/i><div class=\"mdc-button__ripple\"><\/div><span class=\"mdc-button__label\">Lire l&rsquo;article sur Lormont.fr<\/span><\/a><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Alors que nous accumulons comme toutes les professions culturelles annulations et reports. Au coeur de la temp\u00eate nous avons eu par la magie des proc\u00e9dures administratives la possibilit\u00e9 de reprendre la tourn\u00e9e de Certains regardent les \u00e9toiles fin mars dernier. Une bulle totalement improbable, dans un th\u00e9\u00e2tre et pour quelques repr\u00e9sentations exclusivement r\u00e9serv\u00e9es au public &hellip; <a href=\"https:\/\/www.collectif4ailes.fr\/blog\/les-improbables-representations\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;Les improbables repr\u00e9sentations&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":5974,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-5873","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite"],"_links":{"self":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/5873","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/comments?post=5873"}],"version-history":[{"count":7,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/5873\/revisions"}],"predecessor-version":[{"id":5978,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/5873\/revisions\/5978"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/media\/5974"}],"wp:attachment":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/media?parent=5873"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/categories?post=5873"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/tags?post=5873"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}