{"id":5503,"date":"2020-09-17T17:28:23","date_gmt":"2020-09-17T15:28:23","guid":{"rendered":"https:\/\/www.collectif4ailes.fr\/blog\/?p=5503"},"modified":"2021-03-18T12:32:57","modified_gmt":"2021-03-18T11:32:57","slug":"mais-regarde-toi-coup-de-projecteur-sur-frederic","status":"publish","type":"post","link":"https:\/\/www.collectif4ailes.fr\/blog\/mais-regarde-toi-coup-de-projecteur-sur-frederic\/","title":{"rendered":"Mais regarde toi ! Coup de projecteur sur Fr\u00e9d\u00e9ric"},"content":{"rendered":"\n<p><strong><a href=\"https:\/\/www.ecoledesloisirs.fr\/auteur\/frederic-chevaux\">Fr\u00e9d\u00e9ric Chevaux<\/a> <\/strong>nous accompagne de nouveau dans cette aventure th\u00e9\u00e2trale et pluridisciplinaire. Il \u00e9tait d\u00e9j\u00e0 aux commandes de l&rsquo;\u00e9criture de <em><a href=\"https:\/\/www.collectif4ailes.fr\/creations\/certains-regardent-les-etoiles\/\">Certains regardent les \u00e9toiles<\/a><\/em> en 2018 et il nous fait le plaisir de poursuivre l&rsquo;aventure avec <em><a href=\"https:\/\/www.collectif4ailes.fr\/creations\/mais-regarde-toi\/\">Mais regarde toi !<\/a> <\/em>pr\u00e9vu pour novembre 2020. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Une \u00e9criture de plateau, une \u00e9criture d&rsquo;adaptation, une \u00e9criture plastique&#8230;<\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"562\" src=\"https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2020\/09\/web-GUI05618guillemot-edited.jpg\" alt=\"photo de r\u00e9p\u00e9titions Mais regarde toi par le collectif quatre ailes avec Fr\u00e9d\u00e9ric Chevaux\" class=\"wp-image-5520\" srcset=\"https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2020\/09\/web-GUI05618guillemot-edited.jpg 1000w, https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2020\/09\/web-GUI05618guillemot-edited-300x169.jpg 300w, https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2020\/09\/web-GUI05618guillemot-edited-768x432.jpg 768w, https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2020\/09\/web-GUI05618guillemot-edited-150x84.jpg 150w\" sizes=\"auto, (max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><figcaption><em>photo : <\/em><a href=\"https:\/\/www.instagram.com\/vann_guillemot\/\">Nicolas Guillemot<\/a><\/figcaption><\/figure>\n\n\n\n<p>Le d\u00e9fi de l&rsquo;\u00e9criture de <em><a href=\"https:\/\/www.collectif4ailes.fr\/creations\/mais-regarde-toi\/\">Mais regarde toi ! <\/a><\/em>est \u00e9norme. D&rsquo;une part parce que nous avons perdu plus de trois mois de travail avec le confinement li\u00e9 \u00e0 la pand\u00e9mie mais surtout parce que c&rsquo;est une approche in\u00e9dite pour nous. Habitu\u00e9s des adaptations et des r\u00e9\u00e9critures  nous avons d\u00e9cid\u00e9 d&rsquo;exp\u00e9rimenter un autre regard pour saisir l&rsquo;adolescence d\u2019aujourd\u2019hui avec la po\u00e9sie et la f\u00e9erie cruelle que sait tisser Fr\u00e9d\u00e9ric. Le spectacle repose sur l&rsquo;inspiration venue de l&rsquo;\u00e9coute du podcast <em><a href=\"https:\/\/www.youtube.com\/playlist?list=PLqdJBm2veFlB0KXQnisZvSiqvNet_TwU7\">Entre<\/a><\/em> saison 1 de Louie Media, l&rsquo;apparition de faits divers violents li\u00e9s \u00e0 l&rsquo;adolescence comme l&rsquo;histoire d&rsquo;Eva\u00eblle 11 ans pouss\u00e9e \u00e0 bout par le harc\u00e8lement et l&rsquo;univers de Lewis Carroll dans <em>De l&rsquo;autre c\u00f4t\u00e9 du miroir<\/em>. <\/p>\n\n\n\n<p>Fr\u00e9d\u00e9ric lors de ces derni\u00e8res r\u00e9p\u00e9titions de septembre est pass\u00e9 par l&rsquo;intense processus d&rsquo;\u00e9criture par le plateau pour nous permettre d&rsquo;exp\u00e9rimenter la dramaturgie, d&rsquo;improviser autour de son texte et de l&rsquo;\u00e9prouver avec le dispositif sc\u00e9nique et audiovisuel.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Un texte en strates<\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"562\" src=\"https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2020\/09\/web-GUI06239guillemot-edited.jpg\" alt=\"photo de r\u00e9p\u00e9titions Mais regarde toi par le collectif quatre ailes avec Fr\u00e9d\u00e9ric Chevaux\" class=\"wp-image-5517\" srcset=\"https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2020\/09\/web-GUI06239guillemot-edited.jpg 1000w, https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2020\/09\/web-GUI06239guillemot-edited-300x169.jpg 300w, https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2020\/09\/web-GUI06239guillemot-edited-768x432.jpg 768w, https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2020\/09\/web-GUI06239guillemot-edited-150x84.jpg 150w\" sizes=\"auto, (max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><figcaption><em>photo : <\/em><a href=\"https:\/\/www.instagram.com\/vann_guillemot\/\">Nicolas Guillemot<\/a><\/figcaption><\/figure>\n\n\n\n<p>Le r\u00e9sultat de tout cela est un texte en strates et en recouvrements. Il y a Anna qui navigue entre r\u00eave et r\u00e9alit\u00e9, vivant au pr\u00e9sent des aventures folles. Il y a au loin une voix myst\u00e9rieuse mais famili\u00e8re \u00e0 Anna qui lui parle comme si elle la connaissait.  Et enfin, il y a tous les personnages et toutes les apparitions qui vont surgir comme dans un jeu d&rsquo;aventures. De cette apparente complexit\u00e9 survient l&rsquo;univers  propre \u00e0 Lewis Carroll, le trouble propre \u00e0 l&rsquo;adolescence et la fantaisie sensible qui unit Fr\u00e9d\u00e9ric au Collectif Quatre Ailes. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Soyons honn\u00eates&#8230;<\/h2>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img decoding=\"async\" src=\"https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2020\/09\/web-GUI05657guillemot-edited.jpg\" alt=\"photo de r\u00e9p\u00e9titions Mais regarde toi par le collectif quatre ailes avec Fr\u00e9d\u00e9ric Chevaux\" class=\"wp-image-5515\" width=\"660\" height=\"371.25\" srcset=\"https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2020\/09\/web-GUI05657guillemot-edited.jpg 1000w, https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2020\/09\/web-GUI05657guillemot-edited-300x169.jpg 300w, https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2020\/09\/web-GUI05657guillemot-edited-768x432.jpg 768w, https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2020\/09\/web-GUI05657guillemot-edited-150x84.jpg 150w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><figcaption><em>photo : <\/em><a href=\"https:\/\/www.instagram.com\/vann_guillemot\/\">Nicolas Guillemot<\/a><\/figcaption><\/figure><\/div>\n\n\n\n<p>Cette \u00e9criture n&rsquo;est pas de tout repos, on se prend la t\u00eate, on se la tape contre les murs, on saigne nos cerveaux, on \u00e9touffe sous nos masques, on a de la bu\u00e9e sur nos lunettes, on se plante des stylos dans la main de d\u00e9saccord, on a les yeux rouges et secs de surdose de traitement de textes, nos techniciens menacent de nous abattre avec un fusil \u00e0 lunette,  les interpr\u00e8tes convulsent de tergiversations sur le plateau et Fr\u00e9d\u00e9ric a fusionn\u00e9 avec l&rsquo;imprimante laser du th\u00e9\u00e2tre. Mais tout \u00e7a c&rsquo;est pour vous, alors on est content ! Rendez-vous en novembre 2020 <\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link\" href=\"https:\/\/web.digitick.com\/mais-regarde-toi-spectacle-enfant-css5-antoinevitezivry-pg51-ei773531.html\">r\u00e9server<\/a><\/div>\n<\/div>\n\n\n","protected":false},"excerpt":{"rendered":"<p>Fr\u00e9d\u00e9ric Chevaux nous accompagne de nouveau dans cette aventure th\u00e9\u00e2trale et pluridisciplinaire. Il \u00e9tait d\u00e9j\u00e0 aux commandes de l&rsquo;\u00e9criture de Certains regardent les \u00e9toiles en 2018 et il nous fait le plaisir de poursuivre l&rsquo;aventure avec Mais regarde toi ! pr\u00e9vu pour novembre 2020. Une \u00e9criture de plateau, une \u00e9criture d&rsquo;adaptation, une \u00e9criture plastique&#8230; Le &hellip; <a href=\"https:\/\/www.collectif4ailes.fr\/blog\/mais-regarde-toi-coup-de-projecteur-sur-frederic\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;Mais regarde toi ! Coup de projecteur sur Fr\u00e9d\u00e9ric&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":5504,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,10],"tags":[403,483],"class_list":["post-5503","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite","category-spectacles-et-creation","tag-mais-regarde-toi","tag-making-off"],"_links":{"self":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/5503","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/comments?post=5503"}],"version-history":[{"count":7,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/5503\/revisions"}],"predecessor-version":[{"id":5854,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/5503\/revisions\/5854"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/media\/5504"}],"wp:attachment":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/media?parent=5503"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/categories?post=5503"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/tags?post=5503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}