{"id":547,"date":"2008-11-23T01:42:17","date_gmt":"2008-11-23T00:42:17","guid":{"rendered":"http:\/\/lamissive.4ailes.free.fr\/wordpress\/?p=547"},"modified":"2008-11-23T01:42:17","modified_gmt":"2008-11-23T00:42:17","slug":"les-dessous-du-projet-rw","status":"publish","type":"post","link":"https:\/\/www.collectif4ailes.fr\/blog\/les-dessous-du-projet-rw\/","title":{"rendered":"Les dessous du Projet RW"},"content":{"rendered":"<p>Nous venons d&rsquo;accoucher !!! Du moins, le 13 novembre dernier&#8230;<\/p>\n<p>Le petit : \u00ab\u00a0<strong>Le projet RW<\/strong> exp\u00e9rimentations a\u00e9riennes en Helv\u00e9tie d&rsquo;apr\u00e8s <em>La promenade<\/em> de Robert Walser\u00a0\u00bb est n\u00e9 \u00e0 14h30.<\/p>\n<p>3 semaines de travail&#8230; c&rsquo;est long mais l&rsquo;accueil du public nous donne le sourire<\/p>\n<p>Les mamans et papas sont heureux et le b\u00e9b\u00e9 se porte bien<\/p>\n<p>La clinique est tr\u00e8s recommandable et le personnel soignant aux petits oignons<\/p>\n<p>Vous pourrez voir l&rsquo;enfant prochainement \u00e0 Ivry (<a href=\"http:\/\/www.theatre-quartiers-ivry.com\/spectacles\/spect03.html\" target=\"_blank\">Th\u00e9\u00e2tre des Quartiers d&rsquo;Ivry<\/a>) et \u00e0 Paris (<a href=\"http:\/\/www.vingtiemetheatre.com\/2008-2009\/templates\/?page=ponctuelles_2\" target=\"_blank\">Vingti\u00e8me th\u00e9\u00e2tre<\/a>)<\/p>\n<p>Mais d&rsquo;ici l\u00e0, nous vous proposons un petit tour d&rsquo;horizon de tout ce que vous ne verrez jamais du spectacle :<\/p>\n<p><object classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" width=\"400\" height=\"267\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"flashvars\" value=\"host=picasaweb.google.fr&amp;captions=1&amp;RGB=0x000000&amp;feed=http%3A%2F%2Fpicasaweb.google.fr%2Fdata%2Ffeed%2Fapi%2Fuser%2Fsupercarotte%2Falbumid%2F5271641198982102417%3Fkind%3Dphoto%26alt%3Drss%26authkey%3D6-BtvJB1WMw\" \/><param name=\"src\" value=\"http:\/\/picasaweb.google.fr\/s\/c\/bin\/slideshow.swf\" \/><embed type=\"application\/x-shockwave-flash\" width=\"400\" height=\"267\" src=\"http:\/\/picasaweb.google.fr\/s\/c\/bin\/slideshow.swf\" flashvars=\"host=picasaweb.google.fr&amp;captions=1&amp;RGB=0x000000&amp;feed=http%3A%2F%2Fpicasaweb.google.fr%2Fdata%2Ffeed%2Fapi%2Fuser%2Fsupercarotte%2Falbumid%2F5271641198982102417%3Fkind%3Dphoto%26alt%3Drss%26authkey%3D6-BtvJB1WMw\"><\/embed><\/object><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nous venons d&rsquo;accoucher !!! Du moins, le 13 novembre dernier&#8230; Le petit : \u00ab\u00a0Le projet RW exp\u00e9rimentations a\u00e9riennes en Helv\u00e9tie d&rsquo;apr\u00e8s La promenade de Robert Walser\u00a0\u00bb est n\u00e9 \u00e0 14h30. 3 semaines de travail&#8230; c&rsquo;est long mais l&rsquo;accueil du public nous donne le sourire Les mamans et papas sont heureux et le b\u00e9b\u00e9 se porte &hellip; <a href=\"https:\/\/www.collectif4ailes.fr\/blog\/les-dessous-du-projet-rw\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;Les dessous du Projet RW&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,10,11],"tags":[],"class_list":["post-547","post","type-post","status-publish","format-standard","hentry","category-actualite","category-spectacles-et-creation","category-vie-du-collectif"],"_links":{"self":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/547","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/comments?post=547"}],"version-history":[{"count":0,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/547\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/media?parent=547"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/categories?post=547"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/tags?post=547"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}