{"id":545,"date":"2008-11-12T02:08:03","date_gmt":"2008-11-12T01:08:03","guid":{"rendered":"http:\/\/lamissive.4ailes.free.fr\/wordpress\/?p=545"},"modified":"2008-11-12T02:08:03","modified_gmt":"2008-11-12T01:08:03","slug":"silence-radio-creation-en-cours","status":"publish","type":"post","link":"https:\/\/www.collectif4ailes.fr\/blog\/silence-radio-creation-en-cours\/","title":{"rendered":"Silence Radio&#8230; Cr\u00e9ation en cours"},"content":{"rendered":"<p>Nous \u00e9tions plein de bonne volont\u00e9 pour vous donner de nos nouvelles chaque jour lors de la cr\u00e9ation du projet RW mais&#8230; nous avons \u00e9t\u00e9 d\u00e9pass\u00e9s par les \u00e9v\u00e9nements, les mauvaises surprises, les trouvailles de derni\u00e8res minutes, les emp\u00eacheurs de cr\u00e9er en rond, l&rsquo;administration, les id\u00e9es qui fusent etc etc<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\"><strong>Alors rendez vous !!! tout simplement le 14 et le 15 novembre \u00e0 Fresnes \ud83d\ude09<\/strong><\/span><\/p>\n<p style=\"text-align: center;\">pour les autres dates voir ici : <a href=\"http:\/\/collectif4ailes.free.fr\" target=\"_blank\">http:\/\/collectif4ailes.free.fr<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nous \u00e9tions plein de bonne volont\u00e9 pour vous donner de nos nouvelles chaque jour lors de la cr\u00e9ation du projet RW mais&#8230; nous avons \u00e9t\u00e9 d\u00e9pass\u00e9s par les \u00e9v\u00e9nements, les mauvaises surprises, les trouvailles de derni\u00e8res minutes, les emp\u00eacheurs de cr\u00e9er en rond, l&rsquo;administration, les id\u00e9es qui fusent etc etc Alors rendez vous !!! tout &hellip; <a href=\"https:\/\/www.collectif4ailes.fr\/blog\/silence-radio-creation-en-cours\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;Silence Radio&#8230; Cr\u00e9ation en cours&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-545","post","type-post","status-publish","format-standard","hentry","category-actualite"],"_links":{"self":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/545","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/comments?post=545"}],"version-history":[{"count":0,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/545\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/media?parent=545"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/categories?post=545"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/tags?post=545"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}