{"id":528,"date":"2008-10-10T11:38:57","date_gmt":"2008-10-10T09:38:57","guid":{"rendered":"http:\/\/lamissive.4ailes.free.fr\/wordpress\/?p=528"},"modified":"2008-10-10T11:38:57","modified_gmt":"2008-10-10T09:38:57","slug":"mc-93-lautre-discours","status":"publish","type":"post","link":"https:\/\/www.collectif4ailes.fr\/blog\/mc-93-lautre-discours\/","title":{"rendered":"MC 93 l&rsquo;autre discours"},"content":{"rendered":"<p><span style=\"font-family: Comic Sans MS;\"><strong><span style=\"text-decoration: underline;\"><big>SOUTIEN \u00c0 LA MC 93<\/big><\/span><\/strong><\/p>\n<p>L&rsquo;ouverture de la MC93, en mars 1980, \u00e9tait l&rsquo;aboutissement de deux d\u00e9cennies de travail artistique et de combats men\u00e9s par tous ceux qui ont particip\u00e9 \u00e0 cette longue pr\u00e9figuration avec le soutien des \u00e9lus des collectivit\u00e9s locales du d\u00e9partement. Et, les b\u00e2timents \u00e9tant enfin sortis de terre et inaugur\u00e9s, il fallut imm\u00e9diatement reprendre la lutte pour obtenir les moyens n\u00e9cessaires \u00e0 leur fonctionnement. Certains se souviennent sans doute que nous sommes rest\u00e9s portes closes un certain temps, un panneau sur la fa\u00e7ade pr\u00e9cisant que le minist\u00e8re de la Culture refusant de tenir ses engagements, il n&rsquo;\u00e9tait pas possible d&rsquo;ouvrir au public&#8230; Certes, nous avons fini par obtenir gain de cause ; mais, au fil des ann\u00e9es et des directions successives, il n&rsquo;a jamais \u00e9t\u00e9 possible de baisser la garde. Ce qui n&rsquo;a pas emp\u00each\u00e9 la MC93 de s&rsquo;affirmer comme une des sc\u00e8nes les plus importantes du paysage artistique europ\u00e9en.<\/p>\n<p>En cela, l&rsquo;histoire de la MC93 n&rsquo;est pas diff\u00e9rente de celle de toutes les structures culturelles, grandes ou petites. Depuis toujours, d\u00e8s lors que le travail de cr\u00e9ation et l&rsquo;invention de formes nouvelles, l&rsquo;action artistique, la volont\u00e9 de favoriser toujours plus la rencontre entre les \u0153uvres et le public le plus large<\/span><span style=\"font-family: Comic Sans MS;\">, d\u00e9rangent, interrogent, contestent, raillent voire d\u00e9noncent le monde tel qu&rsquo;il est, ceux qui refusent le mouvement de la vie et nient l&rsquo;importance de l&rsquo;utopie cr\u00e9atrice, l\u00e9gif\u00e8rent ou inventent des artifices pour dresser des barri\u00e8res devant les lieux o\u00f9 s&rsquo;invente l&rsquo;art de notre temps.<\/p>\n<p>Ce n&rsquo;est pas seulement une OPA, mais un v\u00e9ritable hold-up dont la ministre de la Culture a confi\u00e9 la mise en \u0153uvre \u00e0 ses sbires (\u00e0 partir d&rsquo;une proposition de<\/span> <span style=\"font-family: Comic Sans MS;\">l&rsquo;administratrice de la Com\u00e9die-Fran\u00e7aise<\/span><span style=\"font-family: Comic Sans MS;\">, Muriel Mayette, que cette initiative n&rsquo;honore pas !). Les directeurs de th\u00e9\u00e2tres nationaux n&rsquo;ont, r\u00e9cemment, que tr\u00e8s faiblement protest\u00e9 contre la stagnation de leurs subventions, mais aucun n&rsquo;a eu l&rsquo;id\u00e9e saugrenue de r\u00e9soudre ses probl\u00e8mes en organisant un raid pour coloniser une salle r\u00e9put\u00e9e de la banlieue. Il est vrai que la Com\u00e9die Fran\u00e7aise n&rsquo;en est pas \u00e0 son coup d&rsquo;essai puisqu&rsquo;elle a d\u00e9j\u00e0 tent\u00e9 une d\u00e9centralisation lamentable \u00e0 Gennevilliers.<\/p>\n<p>Il me semble que l&rsquo;heure n&rsquo;est pas \u00e0 la n\u00e9gociation mais \u00e0 l&rsquo;affirmation d&rsquo;un refus cat\u00e9gorique de ce type de \u00ab\u00a0solution\u00a0\u00bb et, surtout, de la m\u00e9thode qui montre le m\u00e9pris dans lequel ce syst\u00e8me tient les artistes et les professionnels. Certes, le temps n&rsquo;est plus o\u00f9 un \u00e9cart de langage d&rsquo;un ministre (nous reprochant de brandir alternativement \u00ab\u00a0la s\u00e9bile et le cocktail Molotov\u00a0\u00bb) mettait, deux jours apr\u00e8s, toute la profession dans la rue, ce qui obligeait Maurice Druon \u00e0 la d\u00e9mission. Cependant, il est temps que chacun prenne conscience de l&rsquo;inanit\u00e9 du repli sur soi et de l&rsquo;individualisme, dans le domaine de la d\u00e9fense d&rsquo;une profession menac\u00e9e.<\/p>\n<p>Il faut, aujourd&rsquo;hui que chaque fois que ce minist\u00e8re m\u00e8ne une attaque contre un lieu de cr\u00e9ation, une \u00e9quipe artistique, une structure culturelle, quelle que soit la taille de cette entreprise, le directeur et ses collaborateurs trouvent \u00e0 leurs c\u00f4t\u00e9s &#8212; engag\u00e9s dans le refus et la r\u00e9sistance &#8212; l&rsquo;ensemble des artistes de toutes disciplines ainsi que les professionnels des corps de m\u00e9tiers intervenants dans la r\u00e9alisation et la diffusion des \u0153uvres. Sans cette mobilisation (dont chacun sait qu&rsquo;elle est extr\u00eamement difficile, ce qui n&#8217;emp\u00eache pas de commencer \u00e0 l&rsquo;organiser), les mauvais coups continueront et il n&rsquo;y aura bient\u00f4t plus rien \u00e0 d\u00e9fendre.<\/p>\n<p>C&rsquo;est pour cette raison (et aussi, bien s\u00fbr, parce que sept ann\u00e9es de pr\u00e9figuration et cinq ann\u00e9es de direction de la MC 93 ont \u00e9t\u00e9 une des p\u00e9riodes les plus passionnantes de ma vie professionnelle), que j&rsquo;ai pens\u00e9 utile de rompre le silence tranquille et la r\u00e9serve de la retraite en assurant Patrick Sommier et son \u00e9quipe de tout mon soutien.<\/p>\n<p>Claude-Olivier Stern<br \/>\n(directeur de la pr\u00e9figuration de la maison de la Culture de la Seine Saint-Denis de 1973 \u00e0 1980, directeur de la MC93 de 1980 \u00e0 1985)<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>SOUTIEN \u00c0 LA MC 93 L&rsquo;ouverture de la MC93, en mars 1980, \u00e9tait l&rsquo;aboutissement de deux d\u00e9cennies de travail artistique et de combats men\u00e9s par tous ceux qui ont particip\u00e9 \u00e0 cette longue pr\u00e9figuration avec le soutien des \u00e9lus des collectivit\u00e9s locales du d\u00e9partement. Et, les b\u00e2timents \u00e9tant enfin sortis de terre et inaugur\u00e9s, il &hellip; <a href=\"https:\/\/www.collectif4ailes.fr\/blog\/mc-93-lautre-discours\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;MC 93 l&rsquo;autre discours&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,8],"tags":[],"class_list":["post-528","post","type-post","status-publish","format-standard","hentry","category-actualite","category-coup-de-dents"],"_links":{"self":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/528","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/comments?post=528"}],"version-history":[{"count":0,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/528\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/media?parent=528"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/categories?post=528"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/tags?post=528"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}