{"id":5008,"date":"2019-06-03T22:56:06","date_gmt":"2019-06-03T20:56:06","guid":{"rendered":"https:\/\/www.collectif4ailes.fr\/blog\/?p=5008"},"modified":"2019-06-03T22:56:07","modified_gmt":"2019-06-03T20:56:07","slug":"un-jardin-video-avec-les-classes-de-lecole-rosa-parks","status":"publish","type":"post","link":"https:\/\/www.collectif4ailes.fr\/blog\/un-jardin-video-avec-les-classes-de-lecole-rosa-parks\/","title":{"rendered":"Un jardin vid\u00e9o avec les classes de l&rsquo;\u00e9cole Rosa Parks"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2019\/06\/Ma-publication-1-1024x683.png\" alt=\"\" class=\"wp-image-5009\" srcset=\"https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2019\/06\/Ma-publication-1-1024x683.png 1024w, https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2019\/06\/Ma-publication-1-300x200.png 300w, https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2019\/06\/Ma-publication-1-768x512.png 768w\" sizes=\"auto, (max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><figcaption>Photos : Annick Bayard Th\u00e9\u00e2tre Antoine Vitez &#8211; sc\u00e8ne d&rsquo;Ivry &#8211;<\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Le jardin d&rsquo;Alice<\/strong> aujourd&rsquo;hui<\/h3>\n\n\n\n<p>Les classes de Cm2 se sont empar\u00e9es du c\u00e9l\u00e8bre passage d&rsquo;Alice dans le jardin de fleurs, des fleurs aux personnalit\u00e9s hautes en couleurs. Chacun des \u00e9l\u00e8ves a pris place devant la cam\u00e9ra pour jouer diff\u00e9rentes expressions film\u00e9es en tr\u00e8s gros plan. Une bande son a \u00e9t\u00e9 constitu\u00e9e des bribes de phrases et de sons qu\u2019ils ont imagin\u00e9s en s\u2019inspirant de leur lecture d\u2019<em>Alice au pays des merveilles<\/em> et <em>De l\u2019autre c\u00f4t\u00e9 du miroir<\/em> : devinettes, chansons, avertissements\u2026 comme dans le jardin que traverse Alice, le spectateur va voir et entendre d\u2019\u00e9tranges fleurs anim\u00e9es.  <\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Venez visiter ce jardin de papier et de vid\u00e9o <\/strong><\/h3>\n\n\n\n<p><strong>Pour en savoir plus <\/strong>: <a href=\"https:\/\/www.collectif4ailes.fr\/blog\/invitation-a-lexposition-des-creations-des-jeunes-divry\/\">consulter l&rsquo;invitation \u00e0 Quelque chose d&rsquo;Alice le 12 juin 2019 de 8h30 \u00e0 20h<\/a><\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>Le jardin d&rsquo;Alice aujourd&rsquo;hui Les classes de Cm2 se sont empar\u00e9es du c\u00e9l\u00e8bre passage d&rsquo;Alice dans le jardin de fleurs, des fleurs aux personnalit\u00e9s hautes en couleurs. Chacun des \u00e9l\u00e8ves a pris place devant la cam\u00e9ra pour jouer diff\u00e9rentes expressions film\u00e9es en tr\u00e8s gros plan. Une bande son a \u00e9t\u00e9 constitu\u00e9e des bribes de phrases &hellip; <a href=\"https:\/\/www.collectif4ailes.fr\/blog\/un-jardin-video-avec-les-classes-de-lecole-rosa-parks\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;Un jardin vid\u00e9o avec les classes de l&rsquo;\u00e9cole Rosa Parks&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[321],"tags":[],"class_list":["post-5008","post","type-post","status-publish","format-standard","hentry","category-residence-territoriale-ivry"],"_links":{"self":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/5008","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/comments?post=5008"}],"version-history":[{"count":2,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/5008\/revisions"}],"predecessor-version":[{"id":5012,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/5008\/revisions\/5012"}],"wp:attachment":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/media?parent=5008"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/categories?post=5008"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/tags?post=5008"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}