{"id":465,"date":"2008-06-25T11:25:45","date_gmt":"2008-06-25T09:25:45","guid":{"rendered":"http:\/\/lamissive.4ailes.free.fr\/wordpress\/?p=465"},"modified":"2016-08-30T20:07:38","modified_gmt":"2016-08-30T18:07:38","slug":"yodel","status":"publish","type":"post","link":"https:\/\/www.collectif4ailes.fr\/blog\/yodel\/","title":{"rendered":"Yodel"},"content":{"rendered":"<p>Vous n&rsquo;etes pas sans ignorer, que notre nouvelle cr\u00e9ation prend ses inspirations en Suisse. Alors on cherche&#8230; et on a trouv\u00e9 le Yodel.<\/p>\n<p>Et dans le Yodel, plusieurs \u00e9coles.\u00a0 Il y a la c\u00e9l\u00e8bre Regina Snyder, suissesse en culotte tyrolienne\u00a0 et brushing rouquin parfait. Le must pour le Collectif Quatre Ailes. Un mod\u00e8le auquel nous essayons de motiver Marine. Et puis il y a les USA&#8230; :\u00a0<a href=\"https:\/\/youtu.be\/B00nfVc4FPI?t=38s\">https:\/\/youtu.be\/B00nfVc4FPI?t=38s%MCEPASTEBIN%<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vous n&rsquo;etes pas sans ignorer, que notre nouvelle cr\u00e9ation prend ses inspirations en Suisse. Alors on cherche&#8230; et on a trouv\u00e9 le Yodel. Et dans le Yodel, plusieurs \u00e9coles.\u00a0 Il y a la c\u00e9l\u00e8bre Regina Snyder, suissesse en culotte tyrolienne\u00a0 et brushing rouquin parfait. Le must pour le Collectif Quatre Ailes. Un mod\u00e8le auquel nous &hellip; <a href=\"https:\/\/www.collectif4ailes.fr\/blog\/yodel\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;Yodel&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-465","post","type-post","status-publish","format-standard","hentry","category-actualite"],"_links":{"self":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/465","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/comments?post=465"}],"version-history":[{"count":3,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/465\/revisions"}],"predecessor-version":[{"id":4265,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/465\/revisions\/4265"}],"wp:attachment":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/media?parent=465"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/categories?post=465"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/tags?post=465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}