{"id":455,"date":"2008-05-09T22:11:21","date_gmt":"2008-05-09T20:11:21","guid":{"rendered":"http:\/\/lamissive.4ailes.free.fr\/wordpress\/?p=455"},"modified":"2008-05-09T22:11:21","modified_gmt":"2008-05-09T20:11:21","slug":"en-farfouillant-dans-nos-archives","status":"publish","type":"post","link":"https:\/\/www.collectif4ailes.fr\/blog\/en-farfouillant-dans-nos-archives\/","title":{"rendered":"En farfouillant dans nos archives"},"content":{"rendered":"<p>Dans le secret de nos cartons, photos et autres bandes vid\u00e9os, nous avons retrouv\u00e9 les images prises lors de l&rsquo;atelier que nous avons men\u00e9 en compagnie des com\u00e9diens pr\u00e9sents pour le festival Experimenta 7 Teatro en Argentine. L&rsquo;accent espagnol est approximatif et les encha\u00eenements confus&#8230; Il s&rsquo;agit plus pour nous d&rsquo;une vid\u00e9o t\u00e9moin d&rsquo;un travail de recherche sur l&rsquo;univers de <strong><em>Sir Semoule ou l&rsquo;Homme r\u00eav\u00e9<\/em><\/strong>, que d&rsquo;un aboutissement. Cette s\u00e9ance de quelques heures r\u00e9unissait des compagnies venues d&rsquo;Argentine, d&rsquo;Espagne, de R\u00e9publique tch\u00e8que, de France, du Br\u00e9sil&#8230;<\/p>\n<p><embed src=\"http:\/\/video.google.com\/googleplayer.swf?docid=-6184832848746716007&amp;hl=fr\" flashvars=\"flashvars\" style=\"width: 400px; height: 326px\" id=\"VideoPlayback\"><\/embed><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans le secret de nos cartons, photos et autres bandes vid\u00e9os, nous avons retrouv\u00e9 les images prises lors de l&rsquo;atelier que nous avons men\u00e9 en compagnie des com\u00e9diens pr\u00e9sents pour le festival Experimenta 7 Teatro en Argentine. L&rsquo;accent espagnol est approximatif et les encha\u00eenements confus&#8230; Il s&rsquo;agit plus pour nous d&rsquo;une vid\u00e9o t\u00e9moin d&rsquo;un travail &hellip; <a href=\"https:\/\/www.collectif4ailes.fr\/blog\/en-farfouillant-dans-nos-archives\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;En farfouillant dans nos archives&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,11],"tags":[],"class_list":["post-455","post","type-post","status-publish","format-standard","hentry","category-carnet-de-voyage","category-vie-du-collectif"],"_links":{"self":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/455","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/comments?post=455"}],"version-history":[{"count":0,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/455\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/media?parent=455"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/categories?post=455"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/tags?post=455"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}