{"id":4456,"date":"2017-05-16T07:40:55","date_gmt":"2017-05-16T05:40:55","guid":{"rendered":"https:\/\/www.collectif4ailes.fr\/blog\/?p=4456"},"modified":"2017-05-16T07:40:55","modified_gmt":"2017-05-16T05:40:55","slug":"dernieres-rencontres-a-rosny-mugby","status":"publish","type":"post","link":"https:\/\/www.collectif4ailes.fr\/blog\/dernieres-rencontres-a-rosny-mugby\/","title":{"rendered":"Derni\u00e8res rencontres \u00e0 Rosny avant Mugby"},"content":{"rendered":"<p style=\"text-align: justify;\">Sur les routes et les chemins de Rosny-sous-Bois, nous sommes \u00e0 la rencontres de nos jeunes spectateurs pour partager ensemble un moment de complicit\u00e9 autour de <em>L&#8217;embranchement de Mugby. <\/em>Et n&rsquo;oubliez pas le 17 et le 18 mai on vous attend dans notre gare de carton pour siffler un d\u00e9part express pour je ne sais o\u00f9&#8230;<\/p>\n<p style=\"text-align: justify;\"><em><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4459\" src=\"https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2017\/05\/IMG_20170515_150328.jpg\" alt=\"\" width=\"3131\" height=\"2317\" srcset=\"https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2017\/05\/IMG_20170515_150328.jpg 3131w, https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2017\/05\/IMG_20170515_150328-300x222.jpg 300w, https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2017\/05\/IMG_20170515_150328-768x568.jpg 768w, https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2017\/05\/IMG_20170515_150328-1024x758.jpg 1024w\" sizes=\"auto, (max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><\/em><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4457\" src=\"https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2017\/05\/IMG_20170515_120040.jpg\" alt=\"\" width=\"763\" height=\"1027\" srcset=\"https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2017\/05\/IMG_20170515_120040.jpg 763w, https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2017\/05\/IMG_20170515_120040-223x300.jpg 223w, https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2017\/05\/IMG_20170515_120040-761x1024.jpg 761w\" sizes=\"auto, (max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 984px) 61vw, (max-width: 1362px) 45vw, 600px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sur les routes et les chemins de Rosny-sous-Bois, nous sommes \u00e0 la rencontres de nos jeunes spectateurs pour partager ensemble un moment de complicit\u00e9 autour de L&#8217;embranchement de Mugby. Et n&rsquo;oubliez pas le 17 et le 18 mai on vous attend dans notre gare de carton pour siffler un d\u00e9part express pour je ne sais &hellip; <a href=\"https:\/\/www.collectif4ailes.fr\/blog\/dernieres-rencontres-a-rosny-mugby\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;Derni\u00e8res rencontres \u00e0 Rosny avant Mugby&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-4456","post","type-post","status-publish","format-standard","hentry","category-actualite"],"_links":{"self":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/4456","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/comments?post=4456"}],"version-history":[{"count":2,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/4456\/revisions"}],"predecessor-version":[{"id":4461,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/4456\/revisions\/4461"}],"wp:attachment":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/media?parent=4456"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/categories?post=4456"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/tags?post=4456"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}