{"id":4441,"date":"2017-05-10T10:20:59","date_gmt":"2017-05-10T08:20:59","guid":{"rendered":"https:\/\/www.collectif4ailes.fr\/blog\/?p=4441"},"modified":"2017-05-02T00:36:24","modified_gmt":"2017-05-01T22:36:24","slug":"dernieres-representations-de-lembranchement-de-mugby","status":"publish","type":"post","link":"https:\/\/www.collectif4ailes.fr\/blog\/dernieres-representations-de-lembranchement-de-mugby\/","title":{"rendered":"Derni\u00e8res repr\u00e9sentations de L&#8217;embranchement de Mugby"},"content":{"rendered":"<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4238\" src=\"https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2015\/03\/bandeau-Mugby-affiche.jpg\" alt=\"\" width=\"716\" height=\"280\" srcset=\"https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2015\/03\/bandeau-Mugby-affiche.jpg 716w, https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2015\/03\/bandeau-Mugby-affiche-300x117.jpg 300w\" sizes=\"auto, (max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 984px) 61vw, (max-width: 1362px) 45vw, 600px\" \/>Pour voir ou revoir une derni\u00e8re fois notre derni\u00e8re cr\u00e9ation <strong><em>L&#8217;embranchement de Mugby<\/em><\/strong> d&rsquo;apr\u00e8s l&rsquo;oeuvre de Charles Dickens il reste 3 repr\u00e9sentations \u00e0 Rosny sous bois (16 minutes de Gare du Nord en RER).<\/p>\n<p style=\"text-align: justify;\">Nous jouerons les 17 mai (14h30) et 18 mai (10h et 14h30) \u00a0\u00e0 <a href=\"http:\/\/www.rosny93.fr\/Theatre-jeune-public-L#.WQe2Z4nyjOR\" target=\"_blank\" rel=\"noopener noreferrer\">L&rsquo;espace Georges Simenon<\/a> place carnot \u00e0 Rosny. Les places sont disponibles entre 5 et 3 euros directement aupr\u00e8s du th\u00e9\u00e2tre (<a href=\"http:\/\/www.rosny93.fr\/Theatre-jeune-public-L#.WQe2Z4nyjOR\" target=\"_blank\" rel=\"noopener noreferrer\">site web<\/a>) ou en nous contactant.<\/p>\n<p><iframe loading=\"lazy\" title=\"L&#039;embranchement de Mugby (bande annonce)\" width=\"840\" height=\"473\" src=\"https:\/\/www.youtube.com\/embed\/jgQ6J88PB9I?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pour voir ou revoir une derni\u00e8re fois notre derni\u00e8re cr\u00e9ation L&#8217;embranchement de Mugby d&rsquo;apr\u00e8s l&rsquo;oeuvre de Charles Dickens il reste 3 repr\u00e9sentations \u00e0 Rosny sous bois (16 minutes de Gare du Nord en RER). Nous jouerons les 17 mai (14h30) et 18 mai (10h et 14h30) \u00a0\u00e0 L&rsquo;espace Georges Simenon place carnot \u00e0 Rosny. Les &hellip; <a href=\"https:\/\/www.collectif4ailes.fr\/blog\/dernieres-representations-de-lembranchement-de-mugby\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;Derni\u00e8res repr\u00e9sentations de L&#8217;embranchement de Mugby&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-4441","post","type-post","status-publish","format-standard","hentry","category-spectacles-et-creation"],"_links":{"self":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/4441","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/comments?post=4441"}],"version-history":[{"count":2,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/4441\/revisions"}],"predecessor-version":[{"id":4443,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/4441\/revisions\/4443"}],"wp:attachment":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/media?parent=4441"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/categories?post=4441"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/tags?post=4441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}