{"id":444,"date":"2008-03-26T11:26:10","date_gmt":"2008-03-26T10:26:10","guid":{"rendered":"http:\/\/lamissive.4ailes.free.fr\/wordpress\/?p=444"},"modified":"2008-03-26T11:26:10","modified_gmt":"2008-03-26T10:26:10","slug":"le-numero-dobjet-le-courrier","status":"publish","type":"post","link":"https:\/\/www.collectif4ailes.fr\/blog\/le-numero-dobjet-le-courrier\/","title":{"rendered":"Le num\u00e9ro d&rsquo;objet&#8230; le courrier"},"content":{"rendered":"<p>Ci-dessous la lettre d&rsquo;information que nous venons de recevoir.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/lamissive.4ailes.free.fr\/wordpress\/wp-content\/scan.jpeg\" alt=\"num objet\" height=\"740\" width=\"540\" \/><\/p>\n<p>Le lien vers les questions r\u00e9ponses est ici : <a href=\"http:\/\/info.assedic.fr\/assurance_chomage\/travail\/documents\/QR.pdf\" target=\"_blank\">http:\/\/info.assedic.fr\/assurance_chomage\/travail\/documents\/QR.pdf<\/a><\/p>\n<p>A noter que des contradictions apparaissent dans ce document et que de nombreuses questions pratiques quant \u00e0 la r\u00e9alit\u00e9 de certains postes n&rsquo;ont pas du tout \u00e9t\u00e9 prises en compte.  Un exemple cit\u00e9 sur la liste Rue d\u00e9crit le cas de l&rsquo;administrateur de production qui par essence n&rsquo;est rattach\u00e9 \u00e0 aucune production sp\u00e9cifique mais peut travailler sur plusieurs  prod en cours de d\u00e9veloppement (donc qui n&rsquo;existent pas).<\/p>\n<p>Une belle aventure administrative&#8230; commence<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ci-dessous la lettre d&rsquo;information que nous venons de recevoir. Le lien vers les questions r\u00e9ponses est ici : http:\/\/info.assedic.fr\/assurance_chomage\/travail\/documents\/QR.pdf A noter que des contradictions apparaissent dans ce document et que de nombreuses questions pratiques quant \u00e0 la r\u00e9alit\u00e9 de certains postes n&rsquo;ont pas du tout \u00e9t\u00e9 prises en compte. Un exemple cit\u00e9 sur la liste &hellip; <a href=\"https:\/\/www.collectif4ailes.fr\/blog\/le-numero-dobjet-le-courrier\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;Le num\u00e9ro d&rsquo;objet&#8230; le courrier&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-444","post","type-post","status-publish","format-standard","hentry","category-coup-de-dents"],"_links":{"self":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/444","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/comments?post=444"}],"version-history":[{"count":0,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/444\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/media?parent=444"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/categories?post=444"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/tags?post=444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}