{"id":3690,"date":"2016-05-14T15:37:21","date_gmt":"2016-05-14T13:37:21","guid":{"rendered":"http:\/\/www.collectif4ailes.fr\/blog\/?p=3690"},"modified":"2016-06-27T00:03:09","modified_gmt":"2016-06-26T22:03:09","slug":"negatif-positif-se-reveler-1","status":"publish","type":"post","link":"https:\/\/www.collectif4ailes.fr\/blog\/negatif-positif-se-reveler-1\/","title":{"rendered":"N\u00e9gatif \/ Positif \u2013 se r\u00e9v\u00e9ler \u2013"},"content":{"rendered":"<p style=\"text-align: justify;\">Dans le cadre des actions culturelles que nous avons r\u00e9alis\u00e9 cette ann\u00e9e dans le d\u00e9partement de l&rsquo;Essonne voici une s\u00e9rie de quelques projets accomplis avec les jeunes 12 \/ 25 ans du territoire :<\/p>\n<p><em><strong>\u00c9pisode 1 :\u00a0N\u00e9gatif \/ Positif &#8211; se r\u00e9v\u00e9ler &#8211;<\/strong><\/em><\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/lPGMe58yhhw?rel=0\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>Classe-relais du coll\u00e8ge Les Sablons (Viry-Ch\u00e2tillon)<\/p>\n<p>Avec la complicit\u00e9 du <strong><em>Mus\u00e9e fran\u00e7ais de la Photographie<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Le projet d\u00e9bute par la visite, exceptionnelle, des r\u00e9serves du mus\u00e9e fran\u00e7ais de la Photographie. Guid\u00e9s par les professionnels qui prennent soin quotidiennement de ses remarquables collections, les jeunes font une s\u00e9lection de photographies pour constituer un mat\u00e9riau de travail unique en son genre. De retour au coll\u00e8ge, chacun travaille ces images, en les projetant sur soi, en s\u2019y incrustant en ombre, en effectuant plusieurs photomontages. Toutes ces exp\u00e9riences sont men\u00e9es individuellement, respectueux du rythme de chacun, de ses \u00e9motions et capacit\u00e9s d\u2019expression, souvent de fa\u00e7on empirique mais toujours accompagn\u00e9 par le travail bienveillant des artistes. Ce temps de r\u00e9sidence s\u2019est structur\u00e9 comme une s\u00e9quence faite de moments de gestion de la vie collective, d\u2019expression individuelle de mal-\u00eatre et d&rsquo;implication forte, \u00e9pisodique mais sinc\u00e8re, dans la production artistique et la rencontre des artistes. Le r\u00e9sultat final n\u2019est en que plus \u00e9mouvant.<\/p>\n<p style=\"text-align: justify;\">\u00e0 suivre..\u2022<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans le cadre des actions culturelles que nous avons r\u00e9alis\u00e9 cette ann\u00e9e dans le d\u00e9partement de l&rsquo;Essonne voici une s\u00e9rie de quelques projets accomplis avec les jeunes 12 \/ 25 ans du territoire : \u00c9pisode 1 :\u00a0N\u00e9gatif \/ Positif &#8211; se r\u00e9v\u00e9ler &#8211; Classe-relais du coll\u00e8ge Les Sablons (Viry-Ch\u00e2tillon) Avec la complicit\u00e9 du Mus\u00e9e fran\u00e7ais &hellip; <a href=\"https:\/\/www.collectif4ailes.fr\/blog\/negatif-positif-se-reveler-1\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;N\u00e9gatif \/ Positif \u2013 se r\u00e9v\u00e9ler \u2013&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[307],"tags":[],"class_list":["post-3690","post","type-post","status-publish","format-standard","hentry","category-clea-departemental-essonne"],"_links":{"self":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/3690","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/comments?post=3690"}],"version-history":[{"count":4,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/3690\/revisions"}],"predecessor-version":[{"id":3694,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/3690\/revisions\/3694"}],"wp:attachment":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/media?parent=3690"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/categories?post=3690"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/tags?post=3690"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}