{"id":3654,"date":"2016-05-06T23:18:34","date_gmt":"2016-05-06T21:18:34","guid":{"rendered":"http:\/\/www.collectif4ailes.fr\/blog\/?p=3654"},"modified":"2016-06-27T00:03:42","modified_gmt":"2016-06-26T22:03:42","slug":"vernissage-clea-essonne","status":"publish","type":"post","link":"https:\/\/www.collectif4ailes.fr\/blog\/vernissage-clea-essonne\/","title":{"rendered":"Invitation au vernissage de notre exposition dans l&rsquo;Essonne"},"content":{"rendered":"<p style=\"text-align: justify;\">Durant plusieurs mois vous avez suivi ici quelques articles relatant nos actions sur le d\u00e9partement de l&rsquo;Essonne. Une immersion aupr\u00e8s de jeunes, de leur quotidien et de celui des structures qui les re\u00e7oivent mais aussi une immersion dans le pr\u00e9cieux\u00a0patrimoine dont dispose le d\u00e9partement du 91.<\/p>\n<p style=\"text-align: justify;\">L&rsquo;unique et fascinant domaine de M\u00e9r\u00e9ville, le c\u00e9l\u00e8bre domaine de Chamarande, le prestigieux Mus\u00e9e Fran\u00e7ais de la Photographie et ses r\u00e9serves mais aussi des p\u00e9pites de ressources\u00a0comme le patrimoine du Cin\u00e9am ou de la Biblioth\u00e8que d\u00e9partementale&#8230;<\/p>\n<p style=\"text-align: justify;\">Une s\u00e9rie d&rsquo;actions qui nous a\u00a0men\u00e9 de services jeunesses en foyers d&rsquo;accueil, en associations et m\u00eame jusque dans la maison d&rsquo;arr\u00eat de Fleury.<\/p>\n<p>Tout cela nous l&rsquo;avons accompli autour de la th\u00e9matique du portrait. Une th\u00e9matique en trois mots : <strong>TOI MOI NOUS<\/strong><\/p>\n<p style=\"text-align: justify;\">Ce sont ces instantan\u00e9s de la jeunesse essonnienne que nous vous invitons \u00e0 d\u00e9couvrir. Qu&rsquo;il s&rsquo;agisse de photos, d&rsquo;installations vid\u00e9o ou de courts-m\u00e9trages. Nous sommes tr\u00e8s fiers du travail accompli, de la fragilit\u00e9 de ces oeuvres et de la g\u00e9n\u00e9rosit\u00e9 de tous les acteurs de cette r\u00e9sidence.<\/p>\n<p style=\"text-align: justify;\">Nous serions tr\u00e8s heureux de vous compter parmi nous le jour du vernissage pour\u00a0recevoir vos r\u00e9actions.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-3656 size-full\" src=\"http:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2016\/05\/image001.jpg\" alt=\"image001\" width=\"559\" height=\"794\" srcset=\"https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2016\/05\/image001.jpg 559w, https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2016\/05\/image001-211x300.jpg 211w\" sizes=\"auto, (max-width: 559px) 85vw, 559px\" \/><\/p>\n<p style=\"text-align: center;\">Rendez vous le 10 mai 2016<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-3657 size-full\" src=\"http:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2016\/05\/image002.jpg\" alt=\"image002\" width=\"559\" height=\"794\" srcset=\"https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2016\/05\/image002.jpg 559w, https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2016\/05\/image002-211x300.jpg 211w\" sizes=\"auto, (max-width: 559px) 85vw, 559px\" \/><\/p>\n<p style=\"text-align: center;\">\u00a0au Th\u00e9\u00e2tre de L&rsquo;Agora \u00e0 Evry \u00e0 14h00<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durant plusieurs mois vous avez suivi ici quelques articles relatant nos actions sur le d\u00e9partement de l&rsquo;Essonne. Une immersion aupr\u00e8s de jeunes, de leur quotidien et de celui des structures qui les re\u00e7oivent mais aussi une immersion dans le pr\u00e9cieux\u00a0patrimoine dont dispose le d\u00e9partement du 91. L&rsquo;unique et fascinant domaine de M\u00e9r\u00e9ville, le c\u00e9l\u00e8bre domaine &hellip; <a href=\"https:\/\/www.collectif4ailes.fr\/blog\/vernissage-clea-essonne\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;Invitation au vernissage de notre exposition dans l&rsquo;Essonne&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[307],"tags":[],"class_list":["post-3654","post","type-post","status-publish","format-standard","hentry","category-clea-departemental-essonne"],"_links":{"self":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/3654","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/comments?post=3654"}],"version-history":[{"count":8,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/3654\/revisions"}],"predecessor-version":[{"id":3674,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/3654\/revisions\/3674"}],"wp:attachment":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/media?parent=3654"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/categories?post=3654"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/tags?post=3654"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}