{"id":347,"date":"2007-10-07T20:08:30","date_gmt":"2007-10-07T18:08:30","guid":{"rendered":"http:\/\/lamissive.4ailes.free.fr\/wordpress\/?p=347"},"modified":"2007-10-07T20:08:30","modified_gmt":"2007-10-07T18:08:30","slug":"carmelle-et-fidel","status":"publish","type":"post","link":"https:\/\/www.collectif4ailes.fr\/blog\/carmelle-et-fidel\/","title":{"rendered":"Carmelle et Fidel"},"content":{"rendered":"<p>Si vous avez un petit moment cette semaine, nous avons d\u00e9couvert un spectacle comme on les aime : sensible, dr\u00f4le, cruel, beau et qui vous laisse un petit quelque chose au fond de vous.<\/p>\n<ul>\n<li><strong><em>Carmelle ou la d\u00e9raison d&rsquo;\u00eatre<\/em><\/strong><\/li>\n<li><strong><em>Fidel ou la n\u00e9cessit\u00e9 du divertissement<\/em><\/strong><\/li>\n<\/ul>\n<p>ALLEZ -Y !!!<\/p>\n<p><a href=\"http:\/\/lamissive.4ailes.free.fr\/wordpress\/wp-content\/tractmail1-copie.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/lamissive.4ailes.free.fr\/wordpress\/wp-content\/tractmail1-copie-thumb.jpg\" id=\"id\" style=\"border: 0px none \" alt=\"tract carmelle\" border=\"0\" height=\"685\" width=\"515\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si vous avez un petit moment cette semaine, nous avons d\u00e9couvert un spectacle comme on les aime : sensible, dr\u00f4le, cruel, beau et qui vous laisse un petit quelque chose au fond de vous. Carmelle ou la d\u00e9raison d&rsquo;\u00eatre Fidel ou la n\u00e9cessit\u00e9 du divertissement ALLEZ -Y !!!<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-347","post","type-post","status-publish","format-standard","hentry","category-complices-amis-comperes-et-acolytes"],"_links":{"self":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/347","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/comments?post=347"}],"version-history":[{"count":0,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/347\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/media?parent=347"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/categories?post=347"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/tags?post=347"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}