{"id":3439,"date":"2016-04-04T08:46:40","date_gmt":"2016-04-04T06:46:40","guid":{"rendered":"http:\/\/www.collectif4ailes.fr\/blog\/?p=3439"},"modified":"2016-06-27T00:04:34","modified_gmt":"2016-06-26T22:04:34","slug":"couverture-de-plaquette-de-saison-pays-de-mormal","status":"publish","type":"post","link":"https:\/\/www.collectif4ailes.fr\/blog\/couverture-de-plaquette-de-saison-pays-de-mormal\/","title":{"rendered":"En couverture de la plaquette de saison du Pays de Mormal"},"content":{"rendered":"<p>Petite surprise de la semaine derni\u00e8re. Damien se retrouve en couverture de la plaquette de saison de la <strong>Communaut\u00e9 de Communes du Pays de Mormal<\/strong>. Une photo prise lors de notre rencontre avec des enseignants et autres curieux du territoire au Th\u00e9\u00e2tre des 3 ch\u00eanes.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-3440 size-large\" src=\"http:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2016\/04\/IMG_20160404_082945-1020x1024.jpg\" alt=\"IMG_20160404_082945\" width=\"840\" height=\"843\" srcset=\"https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2016\/04\/IMG_20160404_082945-1020x1024.jpg 1020w, https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2016\/04\/IMG_20160404_082945-150x150.jpg 150w, https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2016\/04\/IMG_20160404_082945-300x300.jpg 300w, https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2016\/04\/IMG_20160404_082945-768x771.jpg 768w, https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2016\/04\/IMG_20160404_082945-1200x1204.jpg 1200w\" sizes=\"auto, (max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Petite surprise de la semaine derni\u00e8re. Damien se retrouve en couverture de la plaquette de saison de la Communaut\u00e9 de Communes du Pays de Mormal. Une photo prise lors de notre rencontre avec des enseignants et autres curieux du territoire au Th\u00e9\u00e2tre des 3 ch\u00eanes.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[306],"tags":[],"class_list":["post-3439","post","type-post","status-publish","format-standard","hentry","category-clea-pays-de-mormal"],"_links":{"self":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/3439","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/comments?post=3439"}],"version-history":[{"count":2,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/3439\/revisions"}],"predecessor-version":[{"id":3442,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/3439\/revisions\/3442"}],"wp:attachment":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/media?parent=3439"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/categories?post=3439"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/tags?post=3439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}