{"id":3394,"date":"2016-02-25T16:42:17","date_gmt":"2016-02-25T15:42:17","guid":{"rendered":"http:\/\/www.collectif4ailes.fr\/blog\/?p=3394"},"modified":"2016-04-13T17:22:38","modified_gmt":"2016-04-13T15:22:38","slug":"lembranchement-de-mugby-revient-en-mars-a-ivry","status":"publish","type":"post","link":"https:\/\/www.collectif4ailes.fr\/blog\/lembranchement-de-mugby-revient-en-mars-a-ivry\/","title":{"rendered":"L&#8217;embranchement de Mugby revient en mars \u00e0 Ivry"},"content":{"rendered":"<p>Si vous n&rsquo;avez pas pu voir <em>L&#8217;embranchement de Mugby<\/em> (adaptation de The Mugby Junction) de Charles Dickens. Il est encore temps de vous aventurer sur la ligne 7 du M\u00e9tro parisien pour faire halte dans le Th\u00e9\u00e2tre D&rsquo;Ivry &#8211; Antoine Vitez &#8211; Arr\u00eat Mairie d&rsquo;Ivry du 09 au 12 mars 2016.<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.theatre-quartiers-ivry.com\/fr\/la-saison\/spectacles\/undefinedl_embranchement_de_mugby\" target=\"_blank\">Plus d&rsquo;infos ici\u00a0<\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.theatre-quartiers-ivry.com\/fr\/la-saison\/spectacles\/undefinedl_embranchement_de_mugby\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-3401 size-large\" src=\"http:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2016\/02\/flyer-Mugby-731x1024.jpg\" alt=\"flyer-Mugby\" width=\"731\" height=\"1024\" srcset=\"https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2016\/02\/flyer-Mugby-731x1024.jpg 731w, https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2016\/02\/flyer-Mugby-214x300.jpg 214w, https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2016\/02\/flyer-Mugby-768x1075.jpg 768w, https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2016\/02\/flyer-Mugby-1200x1680.jpg 1200w\" sizes=\"auto, (max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 984px) 61vw, (max-width: 1362px) 45vw, 600px\" \/><\/a><a href=\"http:\/\/www.theatre-quartiers-ivry.com\/fr\/la-saison\/spectacles\/undefinedl_embranchement_de_mugby\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3396 size-large\" src=\"http:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2016\/02\/flyer_Mugby_Page_2-732x1024.png\" alt=\"flyer_Mugby_Page_2\" width=\"732\" height=\"1024\" srcset=\"https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2016\/02\/flyer_Mugby_Page_2-732x1024.png 732w, https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2016\/02\/flyer_Mugby_Page_2-214x300.png 214w, https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2016\/02\/flyer_Mugby_Page_2-768x1075.png 768w, https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2016\/02\/flyer_Mugby_Page_2.png 788w\" sizes=\"auto, (max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 984px) 61vw, (max-width: 1362px) 45vw, 600px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si vous n&rsquo;avez pas pu voir L&#8217;embranchement de Mugby (adaptation de The Mugby Junction) de Charles Dickens. Il est encore temps de vous aventurer sur la ligne 7 du M\u00e9tro parisien pour faire halte dans le Th\u00e9\u00e2tre D&rsquo;Ivry &#8211; Antoine Vitez &#8211; Arr\u00eat Mairie d&rsquo;Ivry du 09 au 12 mars 2016. Plus d&rsquo;infos ici\u00a0 &nbsp;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-3394","post","type-post","status-publish","format-standard","hentry","category-actualite"],"_links":{"self":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/3394","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/comments?post=3394"}],"version-history":[{"count":4,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/3394\/revisions"}],"predecessor-version":[{"id":3458,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/3394\/revisions\/3458"}],"wp:attachment":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/media?parent=3394"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/categories?post=3394"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/tags?post=3394"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}