{"id":335,"date":"2007-09-28T08:58:31","date_gmt":"2007-09-28T06:58:31","guid":{"rendered":"http:\/\/lamissive.4ailes.free.fr\/wordpress\/?p=335"},"modified":"2007-09-28T08:58:31","modified_gmt":"2007-09-28T06:58:31","slug":"dominique-zabala-fait-son-vide-grenier","status":"publish","type":"post","link":"https:\/\/www.collectif4ailes.fr\/blog\/dominique-zabala-fait-son-vide-grenier\/","title":{"rendered":"Dominique Zabala fait son vide-grenier"},"content":{"rendered":"<p><a href=\"http:\/\/lamissive.4ailes.free.fr\/wordpress\/wp-content\/zabala.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/lamissive.4ailes.free.fr\/wordpress\/wp-content\/zabala-thumb.jpg\" id=\"id\" style=\"border: 0px none ; margin: 0px 0px 5px\" alt=\"Mise en page 1\" border=\"0\" height=\"239\" width=\"499\" \/><\/a> Bordelais, Bordelaises,<\/p>\n<p>Voici  un vrai coup de coeur pour une artiste vraiment pas comme les autres. Il s&rsquo;agit de Dominique Zabala, chanteuse, com\u00e9dienne, et tout ce qu&rsquo;on veut d&rsquo;ailleurs parce que son imagination n&rsquo;a pas de limites.<\/p>\n<p>Elle vous offre \u00e0 partir du 04 octobre un concert &#8211; vide-grenier. Ces repr\u00e9sentations sont la derni\u00e8re ligne droite de la cr\u00e9ation. L&rsquo;histoire d&rsquo;une femme qui se livre en chanson comme on fouille dans les cartons d&rsquo;un grenier.<\/p>\n<p>Si vous \u00eates sur Bordeaux, filez donc du c\u00f4t\u00e9 du 29 de la rue Ausone [<a href=\"http:\/\/maps.google.fr\/maps?q=29+rue+ausone+bordeaux&amp;ie=UTF8&amp;oe=UTF-8&amp;ll=44.837674,-0.567877&amp;spn=0.005501,0.010042&amp;z=17&amp;iwloc=addr&amp;om=1\" target=\"_blank\">plan<\/a>] pour \u00e9couter ses histoires.<\/p>\n<p>Moi j&rsquo;l&rsquo;adore parce que pour tout vous dire, elle a \u00e9t\u00e9 mon professeur alors que je n&rsquo;\u00e9tais encore qu&rsquo;une petite buse attendant de devenir un vieux vautour.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bordelais, Bordelaises, Voici un vrai coup de coeur pour une artiste vraiment pas comme les autres. Il s&rsquo;agit de Dominique Zabala, chanteuse, com\u00e9dienne, et tout ce qu&rsquo;on veut d&rsquo;ailleurs parce que son imagination n&rsquo;a pas de limites. Elle vous offre \u00e0 partir du 04 octobre un concert &#8211; vide-grenier. Ces repr\u00e9sentations sont la derni\u00e8re ligne &hellip; <a href=\"https:\/\/www.collectif4ailes.fr\/blog\/dominique-zabala-fait-son-vide-grenier\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;Dominique Zabala fait son vide-grenier&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-335","post","type-post","status-publish","format-standard","hentry","category-complices-amis-comperes-et-acolytes"],"_links":{"self":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/335","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/comments?post=335"}],"version-history":[{"count":0,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/335\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/media?parent=335"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/categories?post=335"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/tags?post=335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}