{"id":3212,"date":"2015-05-29T17:00:59","date_gmt":"2015-05-29T15:00:59","guid":{"rendered":"http:\/\/www.collectif4ailes.fr\/blog\/?p=3212"},"modified":"2016-04-15T00:39:09","modified_gmt":"2016-04-14T22:39:09","slug":"apres-une-magnifique-aventure-avec-la-cca-de-larpajonnais-lessonne","status":"publish","type":"post","link":"https:\/\/www.collectif4ailes.fr\/blog\/apres-une-magnifique-aventure-avec-la-cca-de-larpajonnais-lessonne\/","title":{"rendered":"Apr\u00e8s une magnifique aventure avec la CCA de l&rsquo;Arpajonnais&#8230; L&rsquo;Essonne !!"},"content":{"rendered":"<p style=\"text-align: justify;\">Il y a quelques temps nous avons particip\u00e9 \u00e0 une r\u00e9sidence mission de la Communaut\u00e9 de Communes de l&rsquo;Arpojannais accompagn\u00e9s par l&rsquo;\u00e9quipe de choc et de charme de son service culturel. Apr\u00e8s cette belle aventure main dans la main avec tous les partenaires du territoire nous voil\u00e0 propuls\u00e9s dans une nouvelle odyss\u00e9e\u00a0au niveau d\u00e9partemental. C&rsquo;est tr\u00e8s enthousiastes et impatients que nous attendons le d\u00e9marrage de ce projet autour du portrait et de l&rsquo;image.<\/p>\n<p>On vous en dira plus prochainement.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il y a quelques temps nous avons particip\u00e9 \u00e0 une r\u00e9sidence mission de la Communaut\u00e9 de Communes de l&rsquo;Arpojannais accompagn\u00e9s par l&rsquo;\u00e9quipe de choc et de charme de son service culturel. Apr\u00e8s cette belle aventure main dans la main avec tous les partenaires du territoire nous voil\u00e0 propuls\u00e9s dans une nouvelle odyss\u00e9e\u00a0au niveau d\u00e9partemental. C&rsquo;est &hellip; <a href=\"https:\/\/www.collectif4ailes.fr\/blog\/apres-une-magnifique-aventure-avec-la-cca-de-larpajonnais-lessonne\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;Apr\u00e8s une magnifique aventure avec la CCA de l&rsquo;Arpajonnais&#8230; L&rsquo;Essonne !!&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-3212","post","type-post","status-publish","format-standard","hentry","category-actualite"],"_links":{"self":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/3212","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/comments?post=3212"}],"version-history":[{"count":3,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/3212\/revisions"}],"predecessor-version":[{"id":3500,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/3212\/revisions\/3500"}],"wp:attachment":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/media?parent=3212"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/categories?post=3212"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/tags?post=3212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}