{"id":3195,"date":"2015-05-06T19:43:31","date_gmt":"2015-05-06T17:43:31","guid":{"rendered":"http:\/\/www.collectif4ailes.fr\/blog\/?p=3195"},"modified":"2016-04-15T00:42:59","modified_gmt":"2016-04-14T22:42:59","slug":"prochain-stop-de-mugby-dans-lessonne","status":"publish","type":"post","link":"https:\/\/www.collectif4ailes.fr\/blog\/prochain-stop-de-mugby-dans-lessonne\/","title":{"rendered":"Prochain Stop de Mugby dans l&rsquo;Essonne !!!"},"content":{"rendered":"<p style=\"padding-left: 30px;\"><strong>Rendez vous le 13 mai \u00e0 la salle Pablo Picasso\u00a0<\/strong><\/p>\n<table cellspacing=\"2\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td class=\"intitule couleur\">Lieu<\/td>\n<td class=\"val\">Salle Pablo Picasso \u00e0 20h30<\/td>\n<\/tr>\n<tr>\n<td class=\"intitule couleur\">Adresse<\/td>\n<td class=\"val\">Chemin de la Garenne, face au n\u00b070 &#8211; 91290 La Norville<\/td>\n<\/tr>\n<tr>\n<td class=\"intitule couleur\">T\u00e9l\u00e9phone<\/td>\n<td class=\"val\">01 64 90 93 72<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Pour tout savoir c&rsquo;est par ici :\u00a0<a href=\"http:\/\/www.lanorville91.fr\/fr\/evenement\/104088\/l-embranchement-mugby-collectif-quatre-ailes\" target=\"_blank\">http:\/\/www.lanorville91.fr\/<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rendez vous le 13 mai \u00e0 la salle Pablo Picasso\u00a0 Lieu Salle Pablo Picasso \u00e0 20h30 Adresse Chemin de la Garenne, face au n\u00b070 &#8211; 91290 La Norville T\u00e9l\u00e9phone 01 64 90 93 72 Pour tout savoir c&rsquo;est par ici :\u00a0http:\/\/www.lanorville91.fr\/ &nbsp; &nbsp;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-3195","post","type-post","status-publish","format-standard","hentry","category-actualite"],"_links":{"self":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/3195","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/comments?post=3195"}],"version-history":[{"count":4,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/3195\/revisions"}],"predecessor-version":[{"id":3503,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/3195\/revisions\/3503"}],"wp:attachment":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/media?parent=3195"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/categories?post=3195"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/tags?post=3195"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}