{"id":3162,"date":"2015-01-20T20:57:05","date_gmt":"2015-01-20T19:57:05","guid":{"rendered":"http:\/\/www.collectif4ailes.fr\/blog\/?p=3162"},"modified":"2016-04-13T17:03:56","modified_gmt":"2016-04-13T15:03:56","slug":"telerama-a-publie-une-critique-sur-lembranchement-de-mugby","status":"publish","type":"post","link":"https:\/\/www.collectif4ailes.fr\/blog\/telerama-a-publie-une-critique-sur-lembranchement-de-mugby\/","title":{"rendered":"T\u00e9l\u00e9rama a publi\u00e9 une critique sur l&#8217;embranchement de Mugby"},"content":{"rendered":"<p>Vous pouvez <a href=\"http:\/\/sortir.telerama.fr\/evenements\/spectacles\/l-embranchement-de-mugby,168151.php\" target=\"_blank\">lire l&rsquo;article ici :\u00a0T\u00e9l\u00e9rama<\/a><\/p>\n<p>Et \u00a0conna\u00eetre toutes <a title=\"Que le spectacle commence\u2026\" href=\"http:\/\/www.collectif4ailes.fr\/?page_id=22424\" target=\"_blank\">nos dates de tourn\u00e9e en 2015 ici\u00a0<\/a><\/p>\n<p>\u00e0 bient\u00f4t dans notre embranchement de carton.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vous pouvez lire l&rsquo;article ici :\u00a0T\u00e9l\u00e9rama Et \u00a0conna\u00eetre toutes nos dates de tourn\u00e9e en 2015 ici\u00a0 \u00e0 bient\u00f4t dans notre embranchement de carton.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,10],"tags":[],"class_list":["post-3162","post","type-post","status-publish","format-standard","hentry","category-actualite","category-spectacles-et-creation"],"_links":{"self":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/3162","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/comments?post=3162"}],"version-history":[{"count":4,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/3162\/revisions"}],"predecessor-version":[{"id":3455,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/3162\/revisions\/3455"}],"wp:attachment":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/media?parent=3162"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/categories?post=3162"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/tags?post=3162"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}