{"id":2968,"date":"2014-02-15T14:02:16","date_gmt":"2014-02-15T13:02:16","guid":{"rendered":"http:\/\/www.collectif4ailes.fr\/blog\/?p=2968"},"modified":"2016-04-23T00:50:32","modified_gmt":"2016-04-22T22:50:32","slug":"la-marche-pour-la-culture-ne-fait-que-commencer","status":"publish","type":"post","link":"https:\/\/www.collectif4ailes.fr\/blog\/la-marche-pour-la-culture-ne-fait-que-commencer\/","title":{"rendered":"La marche pour la Culture ne fait que commencer"},"content":{"rendered":"<p style=\"text-align: justify;\">Bon ben voil\u00e0&#8230; Dans la grande famille des \u00a0\u00ab\u00a0retirons les droits aux autres \u00a0\u00bb je voudrais le MEDEF. Qui entre nous soit dit doit compter un nombre non n\u00e9gligeable de &#8230; \u00a0\u00bb un papa une maman, pas d&rsquo;avortement pas de GPA PMA, pas d&rsquo;\u00e9trangers &#8230; \u00ab\u00a0<\/p>\n<p style=\"text-align: justify;\">Donc ces gens d\u00e9licieux ont d\u00e9cid\u00e9 de s&rsquo;en prendre aux intermittents. Pr\u00e9caires niveau 1000 qu&rsquo;il convient de r\u00e9duire \u00e0 n\u00e9ant pour un pourcentage non n\u00e9gligeables d&rsquo;idiots et autres grands groupes audiovisuel qui d\u00e9tournent le syst\u00e8me.<\/p>\n<p style=\"text-align: justify;\">Rien de nouveau sous le soleil&#8230; Des intermittents d&rsquo;accord pour r\u00e9former le syst\u00e8me et des \u00a0\u00bb cr\u00e9ons une pol\u00e9mique sociale de plus avant les municipales histoire de faire avancer la haine pour autrui et les partis de droites \u00a0\u00bb de l&rsquo;autre c\u00f4t\u00e9 \u00a0pour supprimer le r\u00e9gime de protection des intermittents.<\/p>\n<p style=\"text-align: justify;\">Effectivement&#8230; rien de neuf. Sauf qu&rsquo;il ne faut pas se laisser faire. Comme toujours.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-2969\" src=\"http:\/\/collectif4ailes.fr\/blog\/wp-content\/uploads\/2014\/02\/IMG_5164.jpg\" alt=\"IMG_5164\" width=\"216\" height=\"288\" srcset=\"https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2014\/02\/IMG_5164.jpg 600w, https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2014\/02\/IMG_5164-225x300.jpg 225w\" sizes=\"auto, (max-width: 216px) 85vw, 216px\" \/><\/p>\n<p>Alors suivez Micha\u00ebl et marchons pour la Culture.<\/p>\n<p>Merci Anne Marie pour cette photo de la derni\u00e8re marche.<\/p>\n<p><strong>Pour info :<\/strong><\/p>\n<p style=\"text-align: justify;\">A Paris, une assembl\u00e9e g\u00e9n\u00e9rale unitaire le lundi 17 f\u00e9vrier au <a href=\"https:\/\/www.google.fr\/maps\/place\/Th%C3%A9%C3%A2tre+du+Rond-Point\/@48.8677085,2.3105943,17z\/data=!3m1!4b1!4m2!3m1!1s0x0:0x4a0dbcdf60225fed\" target=\"_blank\">th\u00e9\u00e2tre du Rond Point<\/a> \u00a0&#8211; \u00e0 19H \u2013 M\u00e9tro\u00a0: Franklin D. Roosevelt ou Champs-Elys\u00e9es Cl\u00e9menceau<\/p>\n<p style=\"text-align: justify;\">Et sans attendre, nous appelons \u00e0 une manifestation \u00e0 Paris et des initiatives en r\u00e9gions <strong>le 27 f\u00e9vrier<\/strong>, date de la prochaine s\u00e9ance de n\u00e9gociation.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bon ben voil\u00e0&#8230; Dans la grande famille des \u00a0\u00ab\u00a0retirons les droits aux autres \u00a0\u00bb je voudrais le MEDEF. Qui entre nous soit dit doit compter un nombre non n\u00e9gligeable de &#8230; \u00a0\u00bb un papa une maman, pas d&rsquo;avortement pas de GPA PMA, pas d&rsquo;\u00e9trangers &#8230; \u00ab\u00a0 Donc ces gens d\u00e9licieux ont d\u00e9cid\u00e9 de s&rsquo;en prendre &hellip; <a href=\"https:\/\/www.collectif4ailes.fr\/blog\/la-marche-pour-la-culture-ne-fait-que-commencer\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;La marche pour la Culture ne fait que commencer&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,8],"tags":[298,294,299],"class_list":["post-2968","post","type-post","status-publish","format-standard","hentry","category-actualite","category-coup-de-dents","tag-intermittent","tag-je-marche-pour-la-culture","tag-medef"],"_links":{"self":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/2968","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/comments?post=2968"}],"version-history":[{"count":6,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/2968\/revisions"}],"predecessor-version":[{"id":3599,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/2968\/revisions\/3599"}],"wp:attachment":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/media?parent=2968"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/categories?post=2968"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/tags?post=2968"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}