{"id":2814,"date":"2013-06-01T07:46:30","date_gmt":"2013-06-01T05:46:30","guid":{"rendered":"http:\/\/www.collectif4ailes.fr\/blog\/?p=2814"},"modified":"2013-05-29T20:51:58","modified_gmt":"2013-05-29T18:51:58","slug":"jeunes-et-lycees-en-scene-2013","status":"publish","type":"post","link":"https:\/\/www.collectif4ailes.fr\/blog\/jeunes-et-lycees-en-scene-2013\/","title":{"rendered":"Jeunes et Lyc\u00e9es en sc\u00e8ne 2013"},"content":{"rendered":"<p>Nos jeunes val de marnais d\u00e9barquent sur le grand plateau de La sc\u00e8ne Watteau pour 2 soir\u00e9es th\u00e9\u00e2tre. Conclusion de nos\u00a0interventions\u00a0\u00e0 leurs c\u00f4t\u00e9s, ils joueront des spectacles de leurs crus sous les yeux de leurs familles, camarades et autres\u00a0spectateurs\u00a0curieux.<\/p>\n<p>Une exp\u00e9rience unique \u00e0 d\u00e9couvrir les 3 et 4 juin \u00e0 20h30 \u00e0 <a href=\"http:\/\/www.scenewatteau.fr\/Jeunes_en_scene.html\" target=\"_blank\">La sc\u00e8ne Watteau<\/a><\/p>\n<p><a href=\"http:\/\/collectif4ailes.fr\/blog\/wp-content\/uploads\/2013\/05\/couv_1_400x400.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-2815 aligncenter\" alt=\"couv_1_400x400\" src=\"http:\/\/collectif4ailes.fr\/blog\/wp-content\/uploads\/2013\/05\/couv_1_400x400.jpg\" width=\"288\" height=\"400\" srcset=\"https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2013\/05\/couv_1_400x400.jpg 288w, https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2013\/05\/couv_1_400x400-216x300.jpg 216w\" sizes=\"auto, (max-width: 288px) 85vw, 288px\" \/><\/a><\/p>\n<div id=\"ap_listener_added\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Nos jeunes val de marnais d\u00e9barquent sur le grand plateau de La sc\u00e8ne Watteau pour 2 soir\u00e9es th\u00e9\u00e2tre. Conclusion de nos\u00a0interventions\u00a0\u00e0 leurs c\u00f4t\u00e9s, ils joueront des spectacles de leurs crus sous les yeux de leurs familles, camarades et autres\u00a0spectateurs\u00a0curieux. Une exp\u00e9rience unique \u00e0 d\u00e9couvrir les 3 et 4 juin \u00e0 20h30 \u00e0 La sc\u00e8ne Watteau<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-2814","post","type-post","status-publish","format-standard","hentry","category-actualite"],"_links":{"self":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/2814","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/comments?post=2814"}],"version-history":[{"count":3,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/2814\/revisions"}],"predecessor-version":[{"id":2818,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/2814\/revisions\/2818"}],"wp:attachment":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/media?parent=2814"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/categories?post=2814"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/tags?post=2814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}