{"id":281,"date":"2007-08-12T23:46:00","date_gmt":"2007-08-12T21:46:00","guid":{"rendered":"http:\/\/lamissive.4ailes.free.fr\/wordpress\/?p=281"},"modified":"2007-08-12T23:46:00","modified_gmt":"2007-08-12T21:46:00","slug":"le-collectif-recoit-du-courrier-de-bulgarie","status":"publish","type":"post","link":"https:\/\/www.collectif4ailes.fr\/blog\/le-collectif-recoit-du-courrier-de-bulgarie\/","title":{"rendered":"Le collectif re\u00e7oit du courrier de Bulgarie ?!"},"content":{"rendered":"<p>Rien \u00e0 voir avec la cr\u00e9ation de RW, mais bon :<\/p>\n<p>Myst\u00e9rieuse carte postale en forme de Coquille St Jacques&#8230;<\/p>\n<p><a href=\"http:\/\/lamissive.4ailes.free.fr\/wordpress\/wp-content\/image12.jpg\" title=\"carte_bulgarie\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/lamissive.4ailes.free.fr\/wordpress\/wp-content\/image12.jpg\" alt=\"carte_bulgarie\" height=\"429\" width=\"552\" \/><\/a><\/p>\n<p><a href=\"http:\/\/lamissive.4ailes.free.fr\/wordpress\/wp-content\/zimage2.jpg\" title=\"carte_bulgarie_verso3\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/lamissive.4ailes.free.fr\/wordpress\/wp-content\/zimage2.jpg\" alt=\"carte_bulgarie_verso3\" height=\"413\" width=\"553\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rien \u00e0 voir avec la cr\u00e9ation de RW, mais bon : Myst\u00e9rieuse carte postale en forme de Coquille St Jacques&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,7,11],"tags":[],"class_list":["post-281","post","type-post","status-publish","format-standard","hentry","category-actualite","category-coup-de-coeur","category-vie-du-collectif"],"_links":{"self":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/comments?post=281"}],"version-history":[{"count":0,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/281\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/media?parent=281"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/categories?post=281"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/tags?post=281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}