{"id":273,"date":"2007-08-06T14:35:43","date_gmt":"2007-08-06T12:35:43","guid":{"rendered":"http:\/\/lamissive.4ailes.free.fr\/wordpress\/?p=273"},"modified":"2007-08-06T14:35:43","modified_gmt":"2007-08-06T12:35:43","slug":"rw-ca-se-precise","status":"publish","type":"post","link":"https:\/\/www.collectif4ailes.fr\/blog\/rw-ca-se-precise\/","title":{"rendered":"RW \u00e7a se pr\u00e9cise"},"content":{"rendered":"<p>Bient\u00f4t la derni\u00e8re ligne droite !<\/p>\n<p>C&rsquo;est d\u00e9cid\u00e9 nous vous montrerons le chantier les 18 et 19 aout dans l&rsquo;apr\u00e8s midi.\u00a0 Nous vous donnerons les modalit\u00e9s prochainement.<\/p>\n<p>Pour ce qui est de la cr\u00e9ation, le moins que l&rsquo;on puisse dire c&rsquo;est que nous innovons avec notre sens pratique habituel. La derni\u00e8re invention en date c&rsquo;est le plongeoir pour techniciens. Une installation hautement technologique permettant d&rsquo;accrocher des cordes \u00e0 toute vitesse.<\/p>\n<p>Si vous \u00eates sage on vous montrera les coulisses de notre machinerie \u00ab\u00a0Collectif Quatre Ailes\u00a0\u00bb.<\/p>\n<p>Dans un autre registre, nous avons mis \u00e0 jour nos proc\u00e9dures de communication orale. Afin de fluidifier nos \u00e9changes, toute indication de mise en sc\u00e8ne est soumise \u00e0 :<\/p>\n<ul>\n<li>Demandeur : \u00ab\u00a0Il faut entrer \u00e0 jardin\u00a0\u00bb<\/li>\n<li>receveur : \u00ab\u00a0confirmer ?\u00a0\u00bb<\/li>\n<li>Demandeur : \u00ab\u00a0je valide\u00a0\u00bb<\/li>\n<li>receveur : \u00ab\u00a0Correcte !\u00a0\u00bb<\/li>\n<\/ul>\n<p>La demande est r\u00e9alis\u00e9e avec brio 8-))<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bient\u00f4t la derni\u00e8re ligne droite ! C&rsquo;est d\u00e9cid\u00e9 nous vous montrerons le chantier les 18 et 19 aout dans l&rsquo;apr\u00e8s midi.\u00a0 Nous vous donnerons les modalit\u00e9s prochainement. Pour ce qui est de la cr\u00e9ation, le moins que l&rsquo;on puisse dire c&rsquo;est que nous innovons avec notre sens pratique habituel. La derni\u00e8re invention en date c&rsquo;est &hellip; <a href=\"https:\/\/www.collectif4ailes.fr\/blog\/rw-ca-se-precise\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;RW \u00e7a se pr\u00e9cise&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,10,11],"tags":[],"class_list":["post-273","post","type-post","status-publish","format-standard","hentry","category-actualite","category-spectacles-et-creation","category-vie-du-collectif"],"_links":{"self":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/273","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/comments?post=273"}],"version-history":[{"count":0,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/273\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/media?parent=273"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/categories?post=273"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/tags?post=273"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}