{"id":247,"date":"2007-05-30T21:05:09","date_gmt":"2007-05-30T19:05:09","guid":{"rendered":"http:\/\/lamissive.4ailes.free.fr\/wordpress\/?p=247"},"modified":"2007-05-30T21:05:09","modified_gmt":"2007-05-30T19:05:09","slug":"le-theatre-du-rayo-en-danger","status":"publish","type":"post","link":"https:\/\/www.collectif4ailes.fr\/blog\/le-theatre-du-rayo-en-danger\/","title":{"rendered":"Le th\u00e9\u00e2tre du Rayo en danger"},"content":{"rendered":"<p>Une petite info pour vous dire que la compagnie de th\u00e9\u00e2tre le Rayo misterioso qui nous a accueilli en Argentine a perdu son lieu \u00e0 Rosario. Ils ont lanc\u00e9 un appel \u00e0 contribution international pour leur permettre de trouver un nouvel espace.<\/p>\n<p>Nous portons particuli\u00e8rement cette compagnie dans notre coeur car en plus de nous avoir accueilli avec beaucoup de gentillesse ils ont lanc\u00e9 notre tourn\u00e9e internationale.<\/p>\n<p><a href=\"http:\/\/www.elrayomisterioso.org.ar\/espanol\/index.htm\" target=\"_blank\">Pour plus d&rsquo;information sur leurs m\u00e9saventures&#8230; clic<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une petite info pour vous dire que la compagnie de th\u00e9\u00e2tre le Rayo misterioso qui nous a accueilli en Argentine a perdu son lieu \u00e0 Rosario. Ils ont lanc\u00e9 un appel \u00e0 contribution international pour leur permettre de trouver un nouvel espace. Nous portons particuli\u00e8rement cette compagnie dans notre coeur car en plus de nous &hellip; <a href=\"https:\/\/www.collectif4ailes.fr\/blog\/le-theatre-du-rayo-en-danger\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;Le th\u00e9\u00e2tre du Rayo en danger&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,5,6,7,8],"tags":[],"class_list":["post-247","post","type-post","status-publish","format-standard","hentry","category-actualite","category-carnet-de-voyage","category-complices-amis-comperes-et-acolytes","category-coup-de-coeur","category-coup-de-dents"],"_links":{"self":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/247","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/comments?post=247"}],"version-history":[{"count":0,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/247\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/media?parent=247"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/categories?post=247"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/tags?post=247"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}