{"id":227,"date":"2007-05-17T18:04:41","date_gmt":"2007-05-17T16:04:41","guid":{"rendered":"http:\/\/lamissive.4ailes.free.fr\/wordpress\/?p=227"},"modified":"2016-07-30T16:32:55","modified_gmt":"2016-07-30T14:32:55","slug":"mais-au-fait-qui-sommes-nous-1er-volet-claire-corlier","status":"publish","type":"post","link":"https:\/\/www.collectif4ailes.fr\/blog\/mais-au-fait-qui-sommes-nous-1er-volet-claire-corlier\/","title":{"rendered":"Mais, au fait, qui sommes-nous ? 1er volet : Claire Corlier"},"content":{"rendered":"<blockquote>\n<p style=\"text-align: justify;\">Vous qui pensez que l\u2019on devient membre du Collectif Quatre Ailes en invoquant les dieux et en esp\u00e9rant que quelque chose tombe du ciel, ce message vous est destin\u00e9. Il n\u2019en est rien\u2026voici mon histoire pour vous le d\u00e9montrer\u2026<\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-4231 alignleft\" src=\"http:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2007\/05\/claire-corlier.jpg\" alt=\"claire-corlier\" width=\"320\" height=\"320\" srcset=\"https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2007\/05\/claire-corlier.jpg 320w, https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2007\/05\/claire-corlier-150x150.jpg 150w, https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2007\/05\/claire-corlier-300x300.jpg 300w\" sizes=\"auto, (max-width: 320px) 85vw, 320px\" \/>Certaines tantes de ma connaissance (et certainement de la v\u00f4tre) pr\u00e9tendent \u00e0 qui veut l\u2019entendre que j\u2019atteins p\u00e9niblement le niveau du certificat d\u2019\u00e9tudes \u00e0 plus de quarante ans, que mon r\u00eave secret est de retourner vivre dans ma bourgade bourguignonne de M\u00e2con, que je pr\u00e9f\u00e8re que l\u2019on m\u2019appelle Tonton ou l\u2019oncle, que je fus gratifi\u00e9e de quelques sept d\u2019or dans un pass\u00e9 \u00e9loign\u00e9. Je tiens \u00e0 vous rassurer, ce ne sont que des paroles de vieilles femmes rencontr\u00e9es dans des r\u00e9unions Tupperware. Mais, malgr\u00e9 leur s\u00e9nilit\u00e9 avanc\u00e9e, quelques \u00e9l\u00e9ments de v\u00e9rit\u00e9 se sont gliss\u00e9s\u2026<\/p>\n<p style=\"text-align: justify;\"><!-- [if gte vml 1]&amp;gt; --><!-- [if !vml]--><!--[endif]--><\/p>\n<p style=\"text-align: justify;\">Apr\u00e8s avoir pass\u00e9 enfance en plein B\u00e9arn et adolescence dans un village proche de M\u00e2con, je suis arriv\u00e9e bac en poche \u00e0 Dijon pour poursuivre des \u00e9tudes d\u2019anglais. C\u2019est \u00e0 ce moment l\u00e0 que mon parcours th\u00e9\u00e2tral d\u00e9bute, au Th\u00e9\u00e2tre universitaire international de Dijon et au Grenier de Bourgogne (direction Dominique Pitoiset).<\/p>\n<p style=\"text-align: justify;\">Depuis 1992 se sont encha\u00een\u00e9es des p\u00e9riodes d\u2019apprentissage et des p\u00e9riodes de projets, de gestion de troupe et ce jusqu\u2019\u00e0 ce jour \u2026<\/p>\n<p style=\"text-align: justify;\">Voici p\u00eale-m\u00eale les pratiques les plus marquantes abord\u00e9es lors de ces 15 ans de stages et d\u2019ateliers : jeu, improvisation th\u00e9\u00e2trale, cr\u00e9ation de personnages, masque neutre, voix, commedia dell\u2019arte, travesti, clown.<\/p>\n<p style=\"text-align: justify;\">Petits rep\u00e8res chronologiques : En 1994, changement d\u2019orientation universitaire, je me dirige vers le m\u00e9tier de documentaliste et me rapproche de la troupe Nuitd\u2019joi qui vivote alors dans l\u2019enceinte de l\u2019universit\u00e9 : premi\u00e8re exp\u00e9rience de direction de troupe pendant 3 ans, premiers spectacles : <strong><em>Portrait de famille<\/em><\/strong> de L. Pichot puis la <strong><em>Maison<\/em><\/strong><strong><em> de poup\u00e9e<\/em><\/strong> d\u2019Ibsen\u2026viennent ensuite deux ans d\u2019\u00e9criture, de caf\u00e9 th\u00e9\u00e2tre, de th\u00e9\u00e2tre d\u2019intervention, de participation \u00e0 des festivals comme le <strong><em>Festival Primer plano<\/em><\/strong> (Dijon) ou <strong><em>Ch\u00e2lon dans la rue<\/em><\/strong> (off).<\/p>\n<p style=\"text-align: justify;\">La dure r\u00e9alit\u00e9 du monde du travail me rattrape en 1997 o\u00f9 j\u2019atterris dans les tours de la BNF \u00e0 Paris pour mon premier emploi. Pour d\u00e9rider mon quotidien et aborder le th\u00e9\u00e2tre \u00e0 Paris je fais un passage \u00e0 la Ligue d\u2019improvisation d\u2019Ile-de-France puis finis par m\u2019inscrire \u00e0 un cours de th\u00e9\u00e2tre abordant la p\u00e9dagogie <strong>Jacques Lecoq<\/strong>.<\/p>\n<p style=\"text-align: justify;\"><em>Petit appart\u00e9\u2026 Ann\u00e9e 2000, je change de travail et rencontre un certain Damien Saugeon qui en plus de devoir travailler avec moi, partage la passion du th\u00e9\u00e2tre\u2026<\/em><\/p>\n<p style=\"text-align: justify;\"><!--more--><br \/>\nDes rencontres faites durant cet atelier au sein du Teatro Pazzo na\u00eet une troupe \u00ab Mauvaises Langues \u00bb et un projet : <strong><em>Croisements divagations<\/em><\/strong> d\u2019Eug\u00e8ne Durif qui sera jou\u00e9 plus de 15 fois entre 2001 et 2002.<\/p>\n<p style=\"text-align: justify;\">Un certain 11 septembre 2002, une r\u00e9union secr\u00e8te agite quatre cerveaux dans un appartement surnomm\u00e9 d\u00e8s lors \u00ab le berceau \u00bb : et si de deux personnages farfelus (Suzanne et Suzon) qui gravitent dans notre sph\u00e8re depuis plusieurs mois l\u2019on essayait de faire un objet th\u00e9\u00e2tral ? Et si ces amis r\u00e9unissaient leurs univers artistiques pour voir ce qu\u2019il est possible de cr\u00e9er aujourd\u2019hui ?<\/p>\n<p style=\"text-align: justify;\">Vous l\u2019avez certainement compris, c\u2019est le d\u00e9but du Collectif Quatre Ailes et son premier projet <strong><em>Suzanne, Voyage \u00e0 itin\u00e9raires multiples \u00e0 travers la silhouette des choses<\/em><\/strong>. Dans ce spectacle, mon r\u00f4le fut notamment de codiriger avec C\u00e9cile Laffon les deux acteurs Damien Saugeon et Micha\u00ebl Dusautoy dans leur recherche de Suzanne, de diriger les travaux de recherche documentaire (avec Damien), de partir \u00e0 la recherche d\u2019objets ayant appartenus \u00e0 cette vieille femme.<\/p>\n<p style=\"text-align: justify;\">Ne pouvant rester tr\u00e8s longtemps \u00e9loign\u00e9e d\u2019un plateau, j\u2019entreprends en 2003 un atelier au <strong>Th\u00e9\u00e2tre des Quartiers d\u2019Ivry<\/strong> sur le th\u00e8me du travesti et incarne pour une soir\u00e9e <em><strong>Maguilou<\/strong> <\/em>(one woman show)<\/p>\n<p style=\"text-align: justify;\"><!-- [if gte vml 1]&amp;gt; --><!-- [if !vml]--><!--[endif]--><\/p>\n<p style=\"text-align: justify;\">En 2004, l\u2019heure d\u2019une deuxi\u00e8me cr\u00e9ation sonne pour le <strong>Collectif Quatre Ailes<\/strong>, un certain <strong>Sir Semoule<\/strong> arrive dans nos t\u00eates en \u00e9bullition et l\u2019aventure sucr\u00e9e que vous connaissez peut-\u00eatre d\u00e9bute avec son lot d\u2019improvisations, de recherches&#8230; le r\u00f4le de Moritz, petite fille casse-cou en qu\u00eate d\u2019homme r\u00eav\u00e9.<\/p>\n<p style=\"text-align: justify;\"><strong>Voil\u00e0, je m\u2019arr\u00eate ici pour ce p\u00e9rilleux exercice d\u2019autoportrait\u2026 pour garder un peu de suspens quant aux nouvelles aventures du Collectif et passer le relais aux autres membre de cette fine \u00e9quipe !<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vous qui pensez que l\u2019on devient membre du Collectif Quatre Ailes en invoquant les dieux et en esp\u00e9rant que quelque chose tombe du ciel, ce message vous est destin\u00e9. Il n\u2019en est rien\u2026voici mon histoire pour vous le d\u00e9montrer\u2026 Certaines tantes de ma connaissance (et certainement de la v\u00f4tre) pr\u00e9tendent \u00e0 qui veut l\u2019entendre que &hellip; <a href=\"https:\/\/www.collectif4ailes.fr\/blog\/mais-au-fait-qui-sommes-nous-1er-volet-claire-corlier\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;Mais, au fait, qui sommes-nous ? 1er volet : Claire Corlier&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,11],"tags":[],"class_list":["post-227","post","type-post","status-publish","format-standard","hentry","category-actualite","category-vie-du-collectif"],"_links":{"self":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/227","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/comments?post=227"}],"version-history":[{"count":2,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/227\/revisions"}],"predecessor-version":[{"id":4233,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/227\/revisions\/4233"}],"wp:attachment":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/media?parent=227"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/categories?post=227"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/tags?post=227"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}