{"id":2186,"date":"2011-09-13T08:37:55","date_gmt":"2011-09-13T08:37:55","guid":{"rendered":"http:\/\/lamissive.4ailes.free.fr\/wordpress\/?p=2186"},"modified":"2011-12-18T01:39:16","modified_gmt":"2011-12-18T00:39:16","slug":"les-vagues-avec-valentine","status":"publish","type":"post","link":"https:\/\/www.collectif4ailes.fr\/blog\/les-vagues-avec-valentine\/","title":{"rendered":"Les vagues avec Valentine"},"content":{"rendered":"<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"les vagues\" src=\"http:\/\/www.colline.fr\/pics\/0.60364000%201306743354-thumb.jpg\" alt=\"\" width=\"371\" height=\"158\" \/><\/p>\n<p>Petit clin d\u2019\u0153il \u00e0 Valentine qui entame une belle s\u00e9rie de repr\u00e9sentation du spectacle : Les Vagues de Virgina Woolf \u00e0 La Colline du 14\/09 au 15\/10 sur une mise en sc\u00e8ne de M. C Soma.<\/p>\n<p>Plus d&rsquo;infos <a href=\"http:\/\/www.colline.fr\/index.php?page=spectacle&amp;id=355\" target=\"_blank\">en cliquant ici <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Petit clin d\u2019\u0153il \u00e0 Valentine qui entame une belle s\u00e9rie de repr\u00e9sentation du spectacle : Les Vagues de Virgina Woolf \u00e0 La Colline du 14\/09 au 15\/10 sur une mise en sc\u00e8ne de M. C Soma. Plus d&rsquo;infos en cliquant ici<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[138,231],"class_list":["post-2186","post","type-post","status-publish","format-standard","hentry","category-complices-amis-comperes-et-acolytes","tag-les-vagues","tag-valentine-carette"],"_links":{"self":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/2186","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/comments?post=2186"}],"version-history":[{"count":2,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/2186\/revisions"}],"predecessor-version":[{"id":2299,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/2186\/revisions\/2299"}],"wp:attachment":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/media?parent=2186"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/categories?post=2186"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/tags?post=2186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}