{"id":2102,"date":"2011-05-13T11:59:25","date_gmt":"2011-05-13T11:59:25","guid":{"rendered":"http:\/\/lamissive.4ailes.free.fr\/wordpress\/?p=2102"},"modified":"2011-05-13T11:59:25","modified_gmt":"2011-05-13T11:59:25","slug":"retour-du-havre-depart-a-cebazat","status":"publish","type":"post","link":"https:\/\/www.collectif4ailes.fr\/blog\/retour-du-havre-depart-a-cebazat\/","title":{"rendered":"Retour du Havre \/ D\u00e9part \u00e0 C\u00e9bazat"},"content":{"rendered":"<p>De passage rapide \u00e0 Paris voici quelques images de notre baln\u00e9aire parenth\u00e8se dans la douce ville du Havre qui avait programm\u00e9 Le projet RW dans le festival C\u00f4t\u00e9 M\u00f4mes. On a ador\u00e9<\/p>\n<p><embed type=\"application\/x-shockwave-flash\" src=\"https:\/\/picasaweb.google.com\/s\/c\/bin\/slideshow.swf\" width=\"600\" height=\"400\" flashvars=\"host=picasaweb.google.com&#038;hl=fr&#038;feat=flashalbum&#038;RGB=0x000000&#038;feed=https%3A%2F%2Fpicasaweb.google.com%2Fdata%2Ffeed%2Fapi%2Fuser%2F118407087101849716515%2Falbumid%2F5605970516906348337%3Falt%3Drss%26kind%3Dphoto%26authkey%3DGv1sRgCNan3qia5PGIDg%26hl%3Dfr\" pluginspage=\"http:\/\/www.macromedia.com\/go\/getflashplayer\"><\/embed><\/p>\n","protected":false},"excerpt":{"rendered":"<p>De passage rapide \u00e0 Paris voici quelques images de notre baln\u00e9aire parenth\u00e8se dans la douce ville du Havre qui avait programm\u00e9 Le projet RW dans le festival C\u00f4t\u00e9 M\u00f4mes. On a ador\u00e9<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[39,103,134,221],"class_list":["post-2102","post","type-post","status-publish","format-standard","hentry","category-spectacles-et-creation","tag-cote-momes","tag-havre","tag-le-projet-rw","tag-tournee"],"_links":{"self":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/2102","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/comments?post=2102"}],"version-history":[{"count":0,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/2102\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/media?parent=2102"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/categories?post=2102"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/tags?post=2102"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}