{"id":2055,"date":"2011-04-08T11:32:59","date_gmt":"2011-04-08T11:32:59","guid":{"rendered":"http:\/\/lamissive.4ailes.free.fr\/wordpress\/?p=2055"},"modified":"2011-04-08T11:32:59","modified_gmt":"2011-04-08T11:32:59","slug":"encore-quelques-invitations-pour-la-derniere-de-la-belle-au-bois-a-ivry","status":"publish","type":"post","link":"https:\/\/www.collectif4ailes.fr\/blog\/encore-quelques-invitations-pour-la-derniere-de-la-belle-au-bois-a-ivry\/","title":{"rendered":"Encore quelques invitations pour la derni\u00e8re de la Belle au bois \u00e0 Ivry"},"content":{"rendered":"<p><a href=\"http:\/\/collectif4ailes.free.fr\/wordpress\/wp-content\/2010\/11\/Affiche%20La%20Belle%20au%20Bois%20web.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" src=\"http:\/\/collectif4ailes.free.fr\/wordpress\/wp-content\/2010\/11\/Affiche%20La%20Belle%20au%20Bois%20web.jpg\" alt=\"\" width=\"159\" height=\"238\" \/><\/a>C\u00f4t\u00e9 bons plans nous ne sommes pas en reste alors pour f\u00eater ces derni\u00e8res repr\u00e9sentations au <strong>Th\u00e9\u00e2tre des <\/strong><strong>Quartiers d&rsquo;Ivry<\/strong> (M\u00b07 Mairie d&rsquo;Ivry) voil\u00e0 des invitations et tarifs r\u00e9duits sur le grand cybermarch\u00e9 d&rsquo;Internet :<\/p>\n<p><a href=\"http:\/\/www.billetreduc.com\/49334\/evtbook.htm?date=1\">http:\/\/www.billetreduc.com\/49334\/evtbook.htm?date=1<\/a><\/p>\n<p>On esp\u00e8re vous retrouver pour f\u00eater dignement cette aventure en pelote de laine de <em>La Belle au bois<\/em> de Jules Supervielle<\/p>\n","protected":false},"excerpt":{"rendered":"<p>C\u00f4t\u00e9 bons plans nous ne sommes pas en reste alors pour f\u00eater ces derni\u00e8res repr\u00e9sentations au Th\u00e9\u00e2tre des Quartiers d&rsquo;Ivry (M\u00b07 Mairie d&rsquo;Ivry) voil\u00e0 des invitations et tarifs r\u00e9duits sur le grand cybermarch\u00e9 d&rsquo;Internet : http:\/\/www.billetreduc.com\/49334\/evtbook.htm?date=1 On esp\u00e8re vous retrouver pour f\u00eater dignement cette aventure en pelote de laine de La Belle au bois de &hellip; <a href=\"https:\/\/www.collectif4ailes.fr\/blog\/encore-quelques-invitations-pour-la-derniere-de-la-belle-au-bois-a-ivry\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;Encore quelques invitations pour la derni\u00e8re de la Belle au bois \u00e0 Ivry&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,10],"tags":[32,61,117,181,214],"class_list":["post-2055","post","type-post","status-publish","format-standard","hentry","category-actualite","category-spectacles-et-creation","tag-belle-au-bois","tag-collectif-quatre-ailes","tag-jules-supervielle","tag-qui-va-la-les-collectifs","tag-theatre-des-quar"],"_links":{"self":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/2055","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/comments?post=2055"}],"version-history":[{"count":0,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/2055\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/media?parent=2055"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/categories?post=2055"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/tags?post=2055"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}