{"id":190,"date":"2007-04-05T13:56:38","date_gmt":"2007-04-05T11:56:38","guid":{"rendered":"http:\/\/lamissive.4ailes.free.fr\/wordpress\/?p=190"},"modified":"2007-04-05T13:56:38","modified_gmt":"2007-04-05T11:56:38","slug":"le-phenix-et-la-semoule","status":"publish","type":"post","link":"https:\/\/www.collectif4ailes.fr\/blog\/le-phenix-et-la-semoule\/","title":{"rendered":"Le ph\u00e9nix et la semoule"},"content":{"rendered":"<p>Notre pr\u00e9sence \u00e0 Valenciennes (<strong>Ph\u00e9nix <\/strong><em>sc\u00e8ne nationale de Valenciennes<\/em>) a \u00e9t\u00e9 rythm\u00e9e par :<\/p>\n<p>&#8211; 1 atelier en direction du jeune public (les loustixs)<\/p>\n<p>&#8211; 3 repr\u00e9sentations de Sir Semoule<\/p>\n<p>&#8211; De belles rencontres avec toute l&rsquo;\u00e9quipe du Ph\u00e9nix, jeff (le chor\u00e9graphe), franck (le restaurateur de l&rsquo;estaminet \u00e0 tantante), mathieu (le restaurateur de l&rsquo;avant sc\u00e8ne au Ph\u00e9nix), les enfants, le public notamment celui venu tout droit de Belgique&#8230; Mais aussi les poules, les compagnies Joker et Agitez Le Bestiaire.<\/p>\n<p>Un moment d&rsquo;\u00e9motion dans un batiment paquebot plein de portes, de passages secrets, de clefs, de codes, d&rsquo;ascenceurs mysterieux et d&rsquo;escaliers maudits. Tout ce qu&rsquo;on aime !<\/p>\n<table style=\"width: 194px\">\n<tr>\n<td style=\"background: transparent url('http:\/\/picasaweb.google.com\/f\/img\/transparent_album_background.gif') no-repeat scroll left center; height: 194px; -moz-background-clip: -moz-initial; -moz-background-origin: -moz-initial; -moz-background-inline-policy: -moz-initial\" align=\"center\"><a href=\"http:\/\/picasaweb.google.com\/supercarotte\/LePhNix?authkey=VRnAuvZRzAQ\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/lh5.google.com\/image\/supercarotte\/RhLYDqrxAbE\/AAAAAAAAFCQ\/Q1owHrUAqMo\/s160-c\/LePhNix.jpg\" style=\"margin: 1px 0pt 0pt 4px\" height=\"160\" width=\"160\" \/><\/a><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center; font-family: arial,sans-serif; font-size: 11px\"><a href=\"http:\/\/picasaweb.google.com\/supercarotte\/LePhNix?authkey=VRnAuvZRzAQ\" style=\"color: #4d4d4d; font-weight: bold; text-decoration: none\">Le ph\u00e9nix<\/a><\/td>\n<\/tr>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Notre pr\u00e9sence \u00e0 Valenciennes (Ph\u00e9nix sc\u00e8ne nationale de Valenciennes) a \u00e9t\u00e9 rythm\u00e9e par : &#8211; 1 atelier en direction du jeune public (les loustixs) &#8211; 3 repr\u00e9sentations de Sir Semoule &#8211; De belles rencontres avec toute l&rsquo;\u00e9quipe du Ph\u00e9nix, jeff (le chor\u00e9graphe), franck (le restaurateur de l&rsquo;estaminet \u00e0 tantante), mathieu (le restaurateur de l&rsquo;avant sc\u00e8ne &hellip; <a href=\"https:\/\/www.collectif4ailes.fr\/blog\/le-phenix-et-la-semoule\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;Le ph\u00e9nix et la semoule&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,5,10,11],"tags":[],"class_list":["post-190","post","type-post","status-publish","format-standard","hentry","category-actualite","category-carnet-de-voyage","category-spectacles-et-creation","category-vie-du-collectif"],"_links":{"self":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/190","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/comments?post=190"}],"version-history":[{"count":0,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/190\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/media?parent=190"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/categories?post=190"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/tags?post=190"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}