{"id":1805,"date":"2010-10-11T10:00:17","date_gmt":"2010-10-11T10:00:17","guid":{"rendered":"http:\/\/lamissive.4ailes.free.fr\/wordpress\/?p=1805"},"modified":"2010-10-11T10:00:17","modified_gmt":"2010-10-11T10:00:17","slug":"mais-qui-se-cache-derriere-florent-marchet","status":"publish","type":"post","link":"https:\/\/www.collectif4ailes.fr\/blog\/mais-qui-se-cache-derriere-florent-marchet\/","title":{"rendered":"Mais qui se cache derri\u00e8re Florent Marchet ?"},"content":{"rendered":"<p><a href=\"http:\/\/sphotos.ak.fbcdn.net\/hphotos-ak-snc4\/hs386.snc4\/44913_155529911144756_105123819518699_333394_6512318_n.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" title=\"Florent Marchet\" src=\"http:\/\/sphotos.ak.fbcdn.net\/hphotos-ak-snc4\/hs386.snc4\/44913_155529911144756_105123819518699_333394_6512318_n.jpg\" alt=\"\" width=\"251\" height=\"272\" \/><\/a>Et bien Seb, oui, S\u00e9bastien Collinet (le musicien et com\u00e9dien qui a pris la suite de S petit Nico lors de la tourn\u00e9e de Sir Semoule ou l&rsquo;Homme r\u00eav\u00e9). C&rsquo;est un compagnon de route d&rsquo;il y a quelques ann\u00e9es et un musicien fou comme on les aime.<\/p>\n<p>Avec M&rsquo;sieur Marchet, Seb est \u00e0 la guitare, aux claviers et au glockenspiel<\/p>\n<p>Le dernier album<a href=\"http:\/\/www.deezer.com\/fr\/#music\/florent-marchet\/courchevel-672463\" target=\"_blank\"> Courchevel c&rsquo;est ici en \u00e9coute<\/a><\/p>\n<p>Les concerts <a href=\"http:\/\/www.myspace.com\/florentmarchetmusic\" target=\"_blank\">c&rsquo;est par l\u00e0<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Et bien Seb, oui, S\u00e9bastien Collinet (le musicien et com\u00e9dien qui a pris la suite de S petit Nico lors de la tourn\u00e9e de Sir Semoule ou l&rsquo;Homme r\u00eav\u00e9). C&rsquo;est un compagnon de route d&rsquo;il y a quelques ann\u00e9es et un musicien fou comme on les aime. Avec M&rsquo;sieur Marchet, Seb est \u00e0 la guitare, &hellip; <a href=\"https:\/\/www.collectif4ailes.fr\/blog\/mais-qui-se-cache-derriere-florent-marchet\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;Mais qui se cache derri\u00e8re Florent Marchet ?&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[92,193,197],"class_list":["post-1805","post","type-post","status-publish","format-standard","hentry","category-complices-amis-comperes-et-acolytes","tag-florent-marchet","tag-sebastien-collinet","tag-sir-semoule"],"_links":{"self":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/1805","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/comments?post=1805"}],"version-history":[{"count":0,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/1805\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/media?parent=1805"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/categories?post=1805"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/tags?post=1805"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}