{"id":1747,"date":"2010-09-11T20:00:59","date_gmt":"2010-09-11T20:00:59","guid":{"rendered":"http:\/\/lamissive.4ailes.free.fr\/wordpress\/?p=1747"},"modified":"2010-09-11T20:00:59","modified_gmt":"2010-09-11T20:00:59","slug":"joyeux-anniversaire-nous","status":"publish","type":"post","link":"https:\/\/www.collectif4ailes.fr\/blog\/joyeux-anniversaire-nous\/","title":{"rendered":"Joyeux anniversaire nous"},"content":{"rendered":"<p><a href=\"http:\/\/plumsunday.files.wordpress.com\/2008\/07\/miam.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" title=\"macaron\" src=\"http:\/\/plumsunday.files.wordpress.com\/2008\/07\/miam.jpg\" alt=\"\" width=\"231\" height=\"175\" \/><\/a>Oui, le<strong> 11 septembre 2002<\/strong>, il y a 8 ans, un nouvel accident se produisait. La cr\u00e9ation officielle du <strong>Collectif Quatre Ailes <\/strong>au 9 rue du renard, \u00e0 Paris<strong>.<\/strong><\/p>\n<p>8 ans de travail acharn\u00e9, de passions, de spectacles, d&rsquo;id\u00e9es folles, d&rsquo;erreurs, de b\u00eatises, de rencontres, de r\u00e9ussites, d&rsquo;angoisses, de choix, d&rsquo;images, de th\u00e9\u00e2tre, de cirque, de doutes, de grandes certitudes, de voyages, de tourn\u00e9es, de d\u00e9brouille, de budgets, de fichiers diff, de routages, de plan b, de plan c, de plan d, de plan Z, de code rouge, de code noir, de majorette d&rsquo;urgence, de surnoms, de stages, de formation, de remises en question, d&rsquo;affirmation et d&rsquo;histoires bref de spectacles vivants<\/p>\n<p>L&rsquo;aventure continue aujourd&rsquo;hui plus que jamais :<\/p>\n<p>&#8211; L&rsquo;\u00e2ge b\u00eate ?<br \/>\n&#8211; L&rsquo;\u00e2ge ingrat ?<br \/>\n&#8211; L&rsquo;\u00e2ge de raison ?<\/p>\n<p>Comme depuis le premier jour, s\u00fbrement un peu des trois \u00e0 la fois mais pas toujours dans le m\u00eame ordre.<\/p>\n<p>Toutes nos pens\u00e9es \u00e0 nos compagnons de route d&rsquo;hier et d&rsquo;aujourd&rsquo;hui et \u00e0 tout ceux et celles qui nous soutiennent avec tant de conviction et de patience.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Oui, le 11 septembre 2002, il y a 8 ans, un nouvel accident se produisait. La cr\u00e9ation officielle du Collectif Quatre Ailes au 9 rue du renard, \u00e0 Paris. 8 ans de travail acharn\u00e9, de passions, de spectacles, d&rsquo;id\u00e9es folles, d&rsquo;erreurs, de b\u00eatises, de rencontres, de r\u00e9ussites, d&rsquo;angoisses, de choix, d&rsquo;images, de th\u00e9\u00e2tre, de cirque, &hellip; <a href=\"https:\/\/www.collectif4ailes.fr\/blog\/joyeux-anniversaire-nous\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;Joyeux anniversaire nous&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[19,61],"class_list":["post-1747","post","type-post","status-publish","format-standard","hentry","category-vie-du-collectif","tag-anniversaire","tag-collectif-quatre-ailes"],"_links":{"self":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/1747","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/comments?post=1747"}],"version-history":[{"count":0,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/1747\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/media?parent=1747"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/categories?post=1747"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/tags?post=1747"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}