{"id":1691,"date":"2010-07-20T10:16:53","date_gmt":"2010-07-20T10:16:53","guid":{"rendered":"http:\/\/lamissive.4ailes.free.fr\/wordpress\/?p=1691"},"modified":"2016-08-01T11:34:58","modified_gmt":"2016-08-01T09:34:58","slug":"lhorloge-tricoteuse-et-sa-copine-la-lampe","status":"publish","type":"post","link":"https:\/\/www.collectif4ailes.fr\/blog\/lhorloge-tricoteuse-et-sa-copine-la-lampe\/","title":{"rendered":"L&rsquo;horloge tricoteuse et sa copine la lampe&#8230;"},"content":{"rendered":"<p style=\"text-align: justify;\">365 jours pour 2 m d&rsquo;\u00e9charpe, c&rsquo;est ce que propose l&rsquo;horloge de la designer allemande Siren Elise Wilhelmsen.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.trendsnow.net\/2010\/07\/l%E2%80%99horloge-tricoteuse-365.html\" target=\"_blank\">Lire l&rsquo;article sur trendsNow<br \/>\n<\/a><\/p>\n<p style=\"text-align: justify;\">Et en cadeau la lampe Sleeping Beauty de Nadine Sterk : <a href=\"http:\/\/www.ateliernl.com\/site\/sleepingbeauty_more.html\" target=\"_blank\">voir ici<\/a><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" title=\"Sleeping Beauty de Nadine Sterk\" src=\"http:\/\/style-files.com\/images\/ddw7-500x344.jpg\" alt=\"\" width=\"357\" height=\"258\" \/><\/p>\n<p style=\"text-align: justify;\">Oui le tricot nous obs\u00e8de !! Mais vous aussi, quand vous aurez vu notre prochain spectacle\u2026 soyez en s\u00fbrs !!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>365 jours pour 2 m d&rsquo;\u00e9charpe, c&rsquo;est ce que propose l&rsquo;horloge de la designer allemande Siren Elise Wilhelmsen. Lire l&rsquo;article sur trendsNow Et en cadeau la lampe Sleeping Beauty de Nadine Sterk : voir ici Oui le tricot nous obs\u00e8de !! Mais vous aussi, quand vous aurez vu notre prochain spectacle\u2026 soyez en s\u00fbrs !!<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[21,225],"class_list":["post-1691","post","type-post","status-publish","format-standard","hentry","category-actualite","tag-art-contemporain","tag-tricot"],"_links":{"self":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/1691","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/comments?post=1691"}],"version-history":[{"count":2,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/1691\/revisions"}],"predecessor-version":[{"id":4248,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/1691\/revisions\/4248"}],"wp:attachment":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/media?parent=1691"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/categories?post=1691"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/tags?post=1691"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}