{"id":161,"date":"2007-02-09T22:28:58","date_gmt":"2007-02-09T20:28:58","guid":{"rendered":"http:\/\/lamissive.4ailes.free.fr\/wordpress\/?p=161"},"modified":"2007-02-09T22:28:58","modified_gmt":"2007-02-09T20:28:58","slug":"paris-sarajevo-europe","status":"publish","type":"post","link":"https:\/\/www.collectif4ailes.fr\/blog\/paris-sarajevo-europe\/","title":{"rendered":"Paris Sarajevo Europe"},"content":{"rendered":"<p>Comme vous  l&rsquo;avez lu dans notre dernier article, les traductions en bosniens ont \u00e9t\u00e9 r\u00e9alis\u00e9es avec la complicit\u00e9 de l&rsquo;association Paris Sarajevo Europe.<br \/>\nC&rsquo;est Emir Sehic que l&rsquo;on appelle Miro qui nous a apport\u00e9 son soutien.<br \/>\nIl est l&rsquo;actuel responsable de cette association qui existe depuis 1994. Miro est arriv\u00e9 en France en ao\u00fbt 93, ce fut un v\u00e9ritable parcours d&rsquo;obstacles. Mais son acharnement et son engagement b\u00e9n\u00e9vole au sein de Paris Sarajevo lui a permis de s&rsquo;int\u00e9grer pleinement dans sa nouvelle vie.<br \/>\nIl devient salari\u00e9 de l&rsquo;association et s&rsquo;engage dans le lien entre Paris et le <a href=\"http:\/\/www.malraux.ba\/CentreN.htm\" target=\"_blank\">centre Andr\u00e9 Malraux \u00e0 Sarajevo<\/a>.<\/p>\n<p style=\"text-align: center\"><a href=\"http:\/\/www.malraux.ba\/CentreN.htm\" target=\"_blank\"><img decoding=\"async\" src=\"http:\/\/lamissive.4ailes.free.fr\/wordpress\/wp-content\/logo_malraux.miniature.jpg\" alt=\"Centre malraux\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comme vous l&rsquo;avez lu dans notre dernier article, les traductions en bosniens ont \u00e9t\u00e9 r\u00e9alis\u00e9es avec la complicit\u00e9 de l&rsquo;association Paris Sarajevo Europe. C&rsquo;est Emir Sehic que l&rsquo;on appelle Miro qui nous a apport\u00e9 son soutien. Il est l&rsquo;actuel responsable de cette association qui existe depuis 1994. Miro est arriv\u00e9 en France en ao\u00fbt 93, &hellip; <a href=\"https:\/\/www.collectif4ailes.fr\/blog\/paris-sarajevo-europe\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;Paris Sarajevo Europe&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,7],"tags":[],"class_list":["post-161","post","type-post","status-publish","format-standard","hentry","category-actualite","category-coup-de-coeur"],"_links":{"self":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/161","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/comments?post=161"}],"version-history":[{"count":0,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/161\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/media?parent=161"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/categories?post=161"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/tags?post=161"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}