{"id":1543,"date":"2010-04-30T11:55:53","date_gmt":"2010-04-30T09:55:53","guid":{"rendered":"http:\/\/lamissive.4ailes.free.fr\/wordpress\/?p=1543"},"modified":"2016-08-01T11:46:56","modified_gmt":"2016-08-01T09:46:56","slug":"stage-avec-john-strasberg","status":"publish","type":"post","link":"https:\/\/www.collectif4ailes.fr\/blog\/stage-avec-john-strasberg\/","title":{"rendered":"STAGE avec John Strasberg du 7 au 25 juin 2010 \u00e0 Paris"},"content":{"rendered":"<div id=\"id4\">\n<div>\n<div>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-4251\" src=\"http:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2010\/04\/maxresdefault-1024x576.jpg\" alt=\"maxresdefault\" width=\"840\" height=\"473\" srcset=\"https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2010\/04\/maxresdefault-1024x576.jpg 1024w, https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2010\/04\/maxresdefault-300x169.jpg 300w, https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2010\/04\/maxresdefault-768x432.jpg 768w, https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2010\/04\/maxresdefault-1200x675.jpg 1200w, https:\/\/www.collectif4ailes.fr\/blog\/wp-content\/uploads\/2010\/04\/maxresdefault.jpg 1920w\" sizes=\"auto, (max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><\/p>\n<p style=\"text-align: justify;\">La carri\u00e8re internationale d\u2019acteur, metteur en sc\u00e8ne, producteur, concepteur, et auteur de John Strasberg illustre et perp\u00e9tue la tradition artistique de la famille Strasberg. Il a jou\u00e9, enseign\u00e9 et dirig\u00e9 en Europe et en Am\u00e9rique. Il a eu des \u00e9coles \u00e0 New York et \u00e0 Paris, et une compagnie \u00e0 New York, The Mirror Repertory Company, y travaillant avec des artistes comme Geraldine Page. Il a re\u00e7u reconnaissance et r\u00e9compenses, pour des productions de Shakespeare, Aristophane, Pirandello, Ibsen, O\u00b9Neill, et Beckett, entre autres. Il travaille en anglais, en fran\u00e7ais et en espagnol.<\/p>\n<p style=\"text-align: justify;\">Il dirige une classe permanente et des ateliers intensifs \u00e0 New York. Il a un atelier et un th\u00e9\u00e2tre \u00e0 Montr\u00e9al, et voyage \u00e0 travers l\u2019Europe et l\u2019Am\u00e9rique Latine pour y enseigner et y diriger.<br \/>\nLisez : Accidentally on Purpose : Reflections on Life, Acting, and the Nine Natural Laws of Creativity (l\u2019essai profond\u00e9ment personnel de M. Strasberg sur la d\u00e9couverte du processus organique cr\u00e9atif.)<\/p>\n<p style=\"text-align: justify;\">Plus d&rsquo;infos sur le site de la <a href=\"http:\/\/test.lnm.free.fr\/Nez_en_moins\/Stage_JSS.html\" target=\"_blank\">Compagnie du Nez en moins<\/a><\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La carri\u00e8re internationale d\u2019acteur, metteur en sc\u00e8ne, producteur, concepteur, et auteur de John Strasberg illustre et perp\u00e9tue la tradition artistique de la famille Strasberg. Il a jou\u00e9, enseign\u00e9 et dirig\u00e9 en Europe et en Am\u00e9rique. Il a eu des \u00e9coles \u00e0 New York et \u00e0 Paris, et une compagnie \u00e0 New York, The Mirror Repertory &hellip; <a href=\"https:\/\/www.collectif4ailes.fr\/blog\/stage-avec-john-strasberg\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;STAGE avec John Strasberg du 7 au 25 juin 2010 \u00e0 Paris&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[116,124,201],"class_list":["post-1543","post","type-post","status-publish","format-standard","hentry","category-complices-amis-comperes-et-acolytes","tag-john-strasberg","tag-la-compagnie-du-nez-en-moins","tag-stage"],"_links":{"self":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/1543","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/comments?post=1543"}],"version-history":[{"count":2,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/1543\/revisions"}],"predecessor-version":[{"id":4252,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/1543\/revisions\/4252"}],"wp:attachment":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/media?parent=1543"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/categories?post=1543"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/tags?post=1543"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}