{"id":149,"date":"2007-01-20T00:25:49","date_gmt":"2007-01-19T22:25:49","guid":{"rendered":"http:\/\/lamissive.4ailes.free.fr\/wordpress\/?p=149"},"modified":"2007-01-20T00:25:49","modified_gmt":"2007-01-19T22:25:49","slug":"le-collectif-recoit-du-courrier-de-tunisie","status":"publish","type":"post","link":"https:\/\/www.collectif4ailes.fr\/blog\/le-collectif-recoit-du-courrier-de-tunisie\/","title":{"rendered":"Le collectif re\u00e7oit du courrier de Tunisie ?!"},"content":{"rendered":"<p>Il vient de nous arriver une carte d&rsquo;invitation. C&rsquo;est la carte d&rsquo;invitation \u00e0 la c\u00e9r\u00e9monie d&rsquo;ouverture du festival international jeune public N\u00e9apolis&#8230; pour le 18 d\u00e9cembre 2006&#8230;<em \/><\/p>\n<p><em>Lettre post\u00e9e le 06 d\u00e9cembre arriv\u00e9e le 19 janvier. Heureusement que nous ne l&rsquo;avons pas attendu pour nous y rendre \ud83d\ude09<br \/>\n<\/em><\/p>\n<div style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" width=\"338\" height=\"239\" alt=\"enveloppe nabeul\" id=\"image148\" src=\"http:\/\/lamissive.4ailes.free.fr\/wordpress\/wp-content\/enveloppe-invitation.jpg\" \/><\/div>\n<div style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" width=\"371\" height=\"257\" alt=\"Invitation nabeul\" id=\"image147\" src=\"http:\/\/lamissive.4ailes.free.fr\/wordpress\/wp-content\/invitation1.jpg\" \/><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Il vient de nous arriver une carte d&rsquo;invitation. C&rsquo;est la carte d&rsquo;invitation \u00e0 la c\u00e9r\u00e9monie d&rsquo;ouverture du festival international jeune public N\u00e9apolis&#8230; pour le 18 d\u00e9cembre 2006&#8230; Lettre post\u00e9e le 06 d\u00e9cembre arriv\u00e9e le 19 janvier. Heureusement que nous ne l&rsquo;avons pas attendu pour nous y rendre \ud83d\ude09<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,5],"tags":[],"class_list":["post-149","post","type-post","status-publish","format-standard","hentry","category-actualite","category-carnet-de-voyage"],"_links":{"self":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/149","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/comments?post=149"}],"version-history":[{"count":0,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/149\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/media?parent=149"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/categories?post=149"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/tags?post=149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}