{"id":1353,"date":"2010-03-28T19:42:56","date_gmt":"2010-03-28T17:42:56","guid":{"rendered":"http:\/\/lamissive.4ailes.free.fr\/wordpress\/?p=1353"},"modified":"2010-03-28T19:42:56","modified_gmt":"2010-03-28T17:42:56","slug":"depart-pour-la-suisse-le-projet-rw-revient-aux-origines","status":"publish","type":"post","link":"https:\/\/www.collectif4ailes.fr\/blog\/depart-pour-la-suisse-le-projet-rw-revient-aux-origines\/","title":{"rendered":"D\u00e9part pour la Suisse&#8230; Le projet RW revient aux origines"},"content":{"rendered":"<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"Drapeau Suisse\" src=\"http:\/\/a10.idata.over-blog.com\/1\/44\/13\/03\/drapeau_suisse.gif\" alt=\"\" width=\"372\" height=\"218\" \/><\/p>\n<p>C&rsquo;est avec beaucoup d&rsquo;\u00e9motions que nous partons vers la Suisse. Direction La Chaux de Fonds et les terres Walseriennes pour un retour aux sources des promenades de Robert Walser. Le projet RW prend ses quartiers pour quelques jours au Th\u00e9\u00e2tre Populaire Romand et de l&rsquo;Heure Bleue.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>C&rsquo;est avec beaucoup d&rsquo;\u00e9motions que nous partons vers la Suisse. Direction La Chaux de Fonds et les terres Walseriennes pour un retour aux sources des promenades de Robert Walser. Le projet RW prend ses quartiers pour quelques jours au Th\u00e9\u00e2tre Populaire Romand et de l&rsquo;Heure Bleue.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,5],"tags":[123,134,204,219,221],"class_list":["post-1353","post","type-post","status-publish","format-standard","hentry","category-actualite","category-carnet-de-voyage","tag-la-chaux-de-fonds","tag-le-projet-rw","tag-suisse","tag-theatre-populaire-romand-lheure-bleue","tag-tournee"],"_links":{"self":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/1353","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/comments?post=1353"}],"version-history":[{"count":0,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/1353\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/media?parent=1353"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/categories?post=1353"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/tags?post=1353"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}