{"id":1187,"date":"2010-02-17T07:56:04","date_gmt":"2010-02-17T06:56:04","guid":{"rendered":"http:\/\/lamissive.4ailes.free.fr\/wordpress\/?p=1187"},"modified":"2010-02-17T07:56:04","modified_gmt":"2010-02-17T06:56:04","slug":"russie-toujours-mais-en-france-cette-fois","status":"publish","type":"post","link":"https:\/\/www.collectif4ailes.fr\/blog\/russie-toujours-mais-en-france-cette-fois\/","title":{"rendered":"Russie toujours mais en France cette fois"},"content":{"rendered":"<p><strong>Notre ann\u00e9e France &#8211; Russie se poursuit&#8230; <\/strong><\/p>\n<p>Lecture et mise en espace  Samedi 27 f\u00e9vrier \u00e0  16h \u00e0 la m\u00e9diath\u00e8que d&rsquo;Ivry (<a href=\"http:\/\/maps.google.fr\/maps?f=q&amp;source=s_q&amp;hl=fr&amp;geocode=&amp;q=152,+avenue+Danielle+Casanova+ivry&amp;sll=48.813222,2.386265&amp;sspn=0.008153,0.016544&amp;ie=UTF8&amp;hq=&amp;hnear=152+Avenue+Danielle+Casanova,+94200+Ivry-sur-Seine,+Val-de-Marne,+Ile-de-France&amp;ll=48.812417,2.386265&amp;spn=0.008153,0.016544&amp;z=16\" target=\"_blank\">voir le plan<\/a>). On sera sur place si vous voulez nous croiser.<\/p>\n<p>Cette fois c&rsquo;est <strong>Micha\u00ebl <\/strong>qui accompagne<strong> Youlia Zimina<\/strong> pour la mise  en espace de <em>LA FIANC\u00c9E PRUSSIENNE<\/em> de Iouri Bou\u00efda. Cette  collaboration s\u2019ins\u00e8re dans le cycle de mises en espace initi\u00e9 par le <strong>Th\u00e9\u00e2tre  des Quartiers d\u2019Ivry<\/strong> et la <strong>m\u00e9diath\u00e8que d\u2019Ivry,<\/strong> qui ont choisi cette saison d\u2019explorer les \u00e9critures th\u00e9\u00e2trales  contemporaines russes : le th\u00e9\u00e2tre moscovite des fr\u00e8res Presniakov, les  nouvelles de Iouri Bou\u00efda, la correspondance et la po\u00e9sie de Marina  Tsvetaeva\u2026<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" style=\"border: 10px solid white;\" title=\"Iouri Bouida\" src=\"http:\/\/image.evene.fr\/img\/celeb\/17563.jpg\" alt=\"\" width=\"90\" height=\"90\" \/>Les nouvelles de <strong>Iouri Bou\u00efda,<\/strong> originaire de Kaliningrad, sont faites <strong>de situations r\u00e9elles  qui rapidement basculent dans le fantastique et l\u2019improbable.<\/strong> Les fronti\u00e8res sont floues entre les \u00e9poques, les peuples, les \u00e2ges, les  terres. Une femme simple qui ramasse des bouteilles consign\u00e9es, une  employ\u00e9e ordinaire aux pieds de porcelaine, un alcoolique notoire,  r\u00e2leur et insupportable, mais au verbe in\u00e9galable\u2026 Rien n\u2019est d\u00e9fini,  tout est possible, comme dans les contes, comme au th\u00e9\u00e2tre.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.ivry94.fr\/a-laffiche\/details\/evenement\/variations-russes-la-fiancee-prussienne-lectures-russes\/?cHash=1aeefd3d99\" target=\"_blank\">&gt; en savoir plus et r\u00e9server<\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.mymarketing.co.il\/i\/ztzadhdu\/Lectures%20russes.jpg\" target=\"_blank\">&gt; d\u00e9couvrir tout le cycle de lectures autour des auteurs russes<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Notre ann\u00e9e France &#8211; Russie se poursuit&#8230; Lecture et mise en espace Samedi 27 f\u00e9vrier \u00e0 16h \u00e0 la m\u00e9diath\u00e8que d&rsquo;Ivry (voir le plan). On sera sur place si vous voulez nous croiser. Cette fois c&rsquo;est Micha\u00ebl qui accompagne Youlia Zimina pour la mise en espace de LA FIANC\u00c9E PRUSSIENNE de Iouri Bou\u00efda. Cette collaboration &hellip; <a href=\"https:\/\/www.collectif4ailes.fr\/blog\/russie-toujours-mais-en-france-cette-fois\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;Russie toujours mais en France cette fois&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,10,11],"tags":[111,125,149,186,215,235],"class_list":["post-1187","post","type-post","status-publish","format-standard","hentry","category-complices-amis-comperes-et-acolytes","category-spectacles-et-creation","category-vie-du-collectif","tag-iouri-bouida","tag-la-fiancee-prussienne","tag-michael-dusautoy","tag-russie","tag-theatre-des-quartiers-divry","tag-youlia-zimina"],"_links":{"self":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/1187","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/comments?post=1187"}],"version-history":[{"count":0,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/1187\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/media?parent=1187"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/categories?post=1187"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/tags?post=1187"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}