{"id":117,"date":"2006-12-04T16:35:54","date_gmt":"2006-12-04T14:35:54","guid":{"rendered":"http:\/\/lamissive.4ailes.free.fr\/wordpress\/?p=117"},"modified":"2006-12-04T16:35:54","modified_gmt":"2006-12-04T14:35:54","slug":"princes-chameaux-chez-la-nonne","status":"publish","type":"post","link":"https:\/\/www.collectif4ailes.fr\/blog\/princes-chameaux-chez-la-nonne\/","title":{"rendered":"Princes Chameaux chez la Nonne"},"content":{"rendered":"<p>Salut, Salut,<\/p>\n<p>Sachez que les <em><strong>Princes Chameaux<\/strong><\/em> seront au <strong>Nun&rsquo;s caf\u00e9<\/strong> 112 rue saint maure \u00e0 paris 11e [<a target=\"_blank\" href=\"http:\/\/www.google.fr\/maps?f=q&#038;hl=fr&#038;q=112,+Rue+Saint-Maur,+75011+11%C3%A8me+Arrondissement,+Paris&#038;sll=47.15984,2.988281&#038;sspn=40.621923,51.328125&#038;ie=UTF8&#038;z=17&#038;ll=48.866564,2.37516&#038;spn=0.005046,0.013529&#038;om=1&#038;iwloc=addr\">plan<\/a>] les 6 et 7 d\u00e9cembre prochain \u00e0 partir de 20h.<\/p>\n<p>Nous serons donc de passage dans le coin surement jeudi 7.<\/p>\n<p>Les <strong>Princes Chameaux <\/strong>c&rsquo;est un groupe tout fou, g\u00e9n\u00e9reux et authentique. On va dire plut\u00f4t rock mais pas que ?! \ud83d\ude42<\/p>\n<p>Pour ceux qui nous suivent un peu, vous savez surement d\u00e9j\u00e0 que l&rsquo;un des membres du groupe (Seb) est musicien sur <em><strong>Sir Semoule<\/strong><\/em>. Bref, la famille quoi&#8230;<\/p>\n<p>On esp\u00e8re vous voir \u00e0 cette occasion !<\/p>\n<div style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" width=\"322\" height=\"205\" alt=\"Princes chameaux\" id=\"image116\" src=\"http:\/\/lamissive.4ailes.free.fr\/wordpress\/wp-content\/princeschameauxweb.jpg\" \/><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Salut, Salut, Sachez que les Princes Chameaux seront au Nun&rsquo;s caf\u00e9 112 rue saint maure \u00e0 paris 11e [plan] les 6 et 7 d\u00e9cembre prochain \u00e0 partir de 20h. Nous serons donc de passage dans le coin surement jeudi 7. Les Princes Chameaux c&rsquo;est un groupe tout fou, g\u00e9n\u00e9reux et authentique. On va dire plut\u00f4t &hellip; <a href=\"https:\/\/www.collectif4ailes.fr\/blog\/princes-chameaux-chez-la-nonne\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;Princes Chameaux chez la Nonne&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-117","post","type-post","status-publish","format-standard","hentry","category-complices-amis-comperes-et-acolytes"],"_links":{"self":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/117","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/comments?post=117"}],"version-history":[{"count":0,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/posts\/117\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/media?parent=117"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/categories?post=117"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.collectif4ailes.fr\/blog\/wp-json\/wp\/v2\/tags?post=117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}